{"id":13536,"date":"2020-02-12T15:21:48","date_gmt":"2020-02-12T14:21:48","guid":{"rendered":"http:\/\/www.kartingdesfagnes.com\/?page_id=13536"},"modified":"2026-08-31T12:40:47","modified_gmt":"2026-08-31T10:40:47","slug":"kart-fun-trophy-vitesse-fr","status":"publish","type":"page","link":"https:\/\/kartingdesfagnes.be\/nl\/kart-fun-trophy-vitesse-fr\/","title":{"rendered":"Kart Fun Trophy Sprint"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container fusion-parallax-fixed nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility\" style=\"--awb-background-position:right bottom;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:3%;--awb-padding-right:20px;--awb-padding-bottom:111px;--awb-padding-left:20px;--awb-padding-left-small:55px;--awb-margin-bottom:0px;--awb-background-image:linear-gradient(180deg, rgba(0,0,0,0.8) 84%,rgba(255,255,255,0) 100%),url(https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2022\/01\/kart-fun-trophy-sprint-scaled.jpg);;--awb-background-size:cover;background-attachment:fixed;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-row\"><div class=\"fusion-title title fusion-title-1 fusion-no-small-visibility fusion-no-medium-visibility fusion-sep-none fusion-title-center fusion-title-highlight fusion-loop-off fusion-highlight-double fusion-title-size-one\" style=\"--awb-text-color:#ffffff;--awb-highlight-color:#14d500;--awb-highlight-width:6;--awb-margin-bottom:4vh;--awb-font-size:4.6vw;\" data-highlight=\"double\"><h1 class=\"title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.16;\"><span class=\"fusion-highlighted-text-prefix\"><\/span> <span class=\"fusion-highlighted-text-wrapper\"><span class=\"fusion-highlighted-text\">KFT Sprint<\/span><\/span> <span class=\"fusion-highlighted-text-postfix\"><\/span><\/h1><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-animated\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:3%;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:0.64%;--awb-spacing-left-small:1.92%;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.9\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-1 content-boxes-clean-vertical content-left content-boxes-icon-on-top\" style=\"--awb-backgroundcolor:#ffffff;--awb-hover-accent-color:#000000;--awb-circle-hover-accent-color:#000000;--awb-item-margin-bottom:40px;\" data-animationoffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#ffffff;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-box link-type-text content-icon-wrapper-yes icon-wrapper-hover-animation-pulsate fusion-animated\" data-link=\"#resultats\" data-link-target=\"_self\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"#resultats\" target=\"_self\"><div class=\"icon\"><span style=\"height:42px;width:42px;line-height:22px;border-color:rgba(255,255,255,0);border-width:1px;border-style:solid;background-color:#212934;box-sizing:content-box;border-radius:50%;\"><i style=\"border-color:#212934;border-width:1px;background-color:#14d500;box-sizing:content-box;height:40px;width:40px;line-height:40px;border-radius:50%;position:relative;top:auto;left:auto;margin:0;border-radius:50%;font-size:20px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-trophy fas circle-yes\"><\/i><\/span><\/div><h2 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h2_typography-font-size:24px;--fontSize:24;line-height:1.2;\"><b>R\u00c9SULTATS<\/b><\/h2><\/a><\/div><div class=\"fusion-clearfix\"><\/div><a class=\"fusion-read-more\" href=\"#resultats\" target=\"_self\"><b>VOIR<\/b><\/a><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-animated\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:3%;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:0.64%;--awb-spacing-left-small:1.92%;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.9\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-2 content-boxes-clean-vertical content-left content-boxes-icon-on-top\" style=\"--awb-backgroundcolor:#ffffff;--awb-hover-accent-color:#000000;--awb-circle-hover-accent-color:#000000;--awb-item-margin-bottom:40px;\" data-animationoffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#ffffff;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-box link-type-text content-icon-wrapper-yes icon-wrapper-hover-animation-pulsate fusion-animated\" data-link=\"#reservation\" data-link-target=\"_self\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"#reservation\" target=\"_self\"><div class=\"icon\"><span style=\"height:42px;width:42px;line-height:22px;border-color:rgba(255,255,255,0);border-width:1px;border-style:solid;background-color:#212934;box-sizing:content-box;border-radius:50%;\"><i style=\"border-color:#212934;border-width:1px;background-color:#14d500;box-sizing:content-box;height:40px;width:40px;line-height:40px;border-radius:50%;position:relative;top:auto;left:auto;margin:0;border-radius:50%;font-size:20px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-flag-checkered fas circle-yes\"><\/i><\/span><\/div><h2 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h2_typography-font-size:24px;--fontSize:24;line-height:1.2;\"><b>R\u00c9SERVATION<\/b><\/h2><\/a><\/div><div class=\"fusion-clearfix\"><\/div><a class=\"fusion-read-more\" href=\"#reservation\" target=\"_self\"><b>R\u00c9SERVER<\/b><\/a><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-animated\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:3%;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:0.64%;--awb-spacing-left-small:1.92%;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.9\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-3 content-boxes-clean-vertical content-left content-boxes-icon-on-top\" style=\"--awb-backgroundcolor:#ffffff;--awb-hover-accent-color:#000000;--awb-circle-hover-accent-color:#000000;--awb-item-margin-bottom:40px;\" data-animationoffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#ffffff;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-box link-type-text content-icon-wrapper-yes icon-wrapper-hover-animation-pulsate fusion-animated\" data-link=\"#regles\" data-link-target=\"_self\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"#regles\" target=\"_self\"><div class=\"icon\"><span style=\"height:42px;width:42px;line-height:22px;border-color:rgba(255,255,255,0);border-width:1px;border-style:solid;background-color:#212934;box-sizing:content-box;border-radius:50%;\"><i style=\"border-color:#212934;border-width:1px;background-color:#14d500;box-sizing:content-box;height:40px;width:40px;line-height:40px;border-radius:50%;position:relative;top:auto;left:auto;margin:0;border-radius:50%;font-size:20px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-book-open fas circle-yes\"><\/i><\/span><\/div><h2 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h2_typography-font-size:24px;--fontSize:24;line-height:1.2;\"><b>R\u00c8GLEMENT<\/b><\/h2><\/a><\/div><div class=\"fusion-clearfix\"><\/div><a class=\"fusion-read-more\" href=\"#regles\" target=\"_self\"><b>VOIR<\/b><\/a><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-background-position:right bottom;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:3%;--awb-padding-right:20px;--awb-padding-bottom:69px;--awb-padding-left:20px;--awb-padding-bottom-small:19.991500000000002px;--awb-padding-left-small:10px;--awb-margin-bottom:0px;--awb-background-color:#000000;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-padding-bottom-small:24px;--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-margin-top-small:0px;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-row\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-highlight fusion-loop-off fusion-highlight-double fusion-title-size-one\" style=\"--awb-text-color:#ffffff;--awb-highlight-color:#14d500;--awb-highlight-width:6;--awb-margin-bottom:4vh;--awb-font-size:3em;\" data-highlight=\"double\"><h1 class=\"title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:48;line-height:1.16;\"><span class=\"fusion-highlighted-text-prefix\"><\/span> <span class=\"fusion-highlighted-text-wrapper\"><span class=\"fusion-highlighted-text\">Kart Fun Trophy - Sprint<\/span><\/span> <span class=\"fusion-highlighted-text-postfix\"><\/span><\/h1><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"sm-text-align-center\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type fusion-has-button-gradient\" style=\"--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" target=\"_self\" href=\"#inscriptions\"><span class=\"fusion-button-text\">R\u00c9SERVER<\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#000000;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-column-inner-bg-wrapper\" style=\"--awb-padding-top-small:4em;--awb-padding-bottom-small:4em;--awb-overflow:hidden;--awb-inner-bg-size:cover;--awb-box-shadow:5px 5px 7px 1px #14d500;;--awb-border-color:#14d500;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:5% 5% 5% 5%;--awb-inner-bg-border-radius:5% 5% 5% 5%;--awb-inner-bg-overflow:hidden;--awb-width-large:33.333333333333%;--awb-spacing-right-large:5.76%;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"https:\/\/kartingdesfagnes.be\/nl\/kart-fun-trophy-vitesse-fr\/#inscriptions\"><span class=\"fusion-column-inner-bg-image\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><i class=\"fb-icon-element-1 fb-icon-element fontawesome-icon fa-cart-arrow-down fas circle-yes\" style=\"--awb-circlecolor:#14d500;--awb-circlecolor-hover:#00a502;--awb-circlebordercolor:#ffffff;--awb-circlebordercolor-hover:#00a502;--awb-circlebordersize:1px;--awb-font-size:26.4px;--awb-width:52.8px;--awb-height:52.8px;--awb-line-height:50.8px;--awb-margin-top:0;--awb-margin-right:0;--awb-margin-bottom:0;--awb-margin-left:0;--awb-align-self:center;\"><\/i><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-div\" style=\"--awb-text-color:#ffffff;--awb-font-size:4vw;\"><div class=\"title-heading-left title-heading-tag sm-text-align-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.8;\">R\u00c9SERVATION<\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-column-inner-bg-wrapper\" style=\"--awb-padding-top-small:4em;--awb-padding-bottom-small:4em;--awb-overflow:hidden;--awb-inner-bg-size:cover;--awb-box-shadow:5px 5px 7px 1px #ffffff;;--awb-border-color:#ffffff;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:5% 5% 5% 5%;--awb-inner-bg-border-radius:5% 5% 5% 5%;--awb-inner-bg-overflow:hidden;--awb-width-large:33.333333333333%;--awb-spacing-right-large:5.76%;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"https:\/\/kartingdesfagnes.be\/nl\/kart-fun-trophy-vitesse-fr\/#resultats-m\"><span class=\"fusion-column-inner-bg-image\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><i class=\"fb-icon-element-2 fb-icon-element fontawesome-icon fa-trophy fas circle-yes\" style=\"--awb-circlecolor:#14d500;--awb-circlecolor-hover:#00a502;--awb-circlebordercolor:#ffffff;--awb-circlebordercolor-hover:#00a502;--awb-circlebordersize:1px;--awb-font-size:26.4px;--awb-width:52.8px;--awb-height:52.8px;--awb-line-height:50.8px;--awb-margin-top:0;--awb-margin-right:0;--awb-margin-bottom:0;--awb-margin-left:0;--awb-align-self:center;\"><\/i><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-div\" style=\"--awb-text-color:#ffffff;--awb-font-size:4vw;\"><div class=\"title-heading-left title-heading-tag sm-text-align-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.8;\">R\u00c9SULTATS<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#000000;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-column-inner-bg-wrapper\" style=\"--awb-padding-top-small:4em;--awb-padding-bottom-small:4em;--awb-overflow:hidden;--awb-inner-bg-size:cover;--awb-box-shadow:5px 5px 7px 1px #14d500;;--awb-border-color:#14d500;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:5% 5% 5% 5%;--awb-inner-bg-border-radius:5% 5% 5% 5%;--awb-inner-bg-overflow:hidden;--awb-width-large:33.333333333333%;--awb-spacing-right-large:5.76%;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:50%;--awb-order-small:1;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"https:\/\/kartingdesfagnes.be\/nl\/kart-fun-trophy-vitesse-fr\/#regles-m\"><span class=\"fusion-column-inner-bg-image\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><i class=\"fb-icon-element-3 fb-icon-element fontawesome-icon fa-book-open fas circle-yes\" style=\"--awb-circlecolor:#14d500;--awb-circlecolor-hover:#00a502;--awb-circlebordercolor:#ffffff;--awb-circlebordercolor-hover:#00a502;--awb-circlebordersize:1px;--awb-font-size:26.4px;--awb-width:52.8px;--awb-height:52.8px;--awb-line-height:50.8px;--awb-margin-top:0;--awb-margin-right:0;--awb-margin-bottom:0;--awb-margin-left:0;--awb-align-self:center;\"><\/i><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-div\" style=\"--awb-text-color:#ffffff;--awb-font-size:4vw;\"><div class=\"title-heading-left title-heading-tag sm-text-align-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.8;\">R\u00c8GLEMENT<\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-column-inner-bg-wrapper\" style=\"--awb-padding-top-small:4em;--awb-padding-bottom-small:4em;--awb-overflow:hidden;--awb-inner-bg-size:cover;--awb-box-shadow:5px 5px 7px 1px #ffffff;;--awb-border-color:#ffffff;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:5% 5% 5% 5%;--awb-inner-bg-border-radius:5% 5% 5% 5%;--awb-inner-bg-overflow:hidden;--awb-width-large:33.333333333333%;--awb-spacing-right-large:5.76%;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"https:\/\/kartingdesfagnes.be\/nl\/kart-fun-trophy-vitesse-fr\/#calendrier-m\"><span class=\"fusion-column-inner-bg-image\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><i class=\"fb-icon-element-4 fb-icon-element fontawesome-icon fa-calendar-alt fas circle-yes\" style=\"--awb-circlecolor:#14d500;--awb-circlecolor-hover:#00a502;--awb-circlebordercolor:#ffffff;--awb-circlebordercolor-hover:#00a502;--awb-circlebordersize:1px;--awb-font-size:26.4px;--awb-width:52.8px;--awb-height:52.8px;--awb-line-height:50.8px;--awb-margin-top:0;--awb-margin-right:0;--awb-margin-bottom:0;--awb-margin-left:0;--awb-align-self:center;\"><\/i><div class=\"fusion-title title fusion-title-6 fusion-sep-none fusion-title-text fusion-title-size-div\" style=\"--awb-text-color:#ffffff;--awb-font-size:4vw;\"><div class=\"title-heading-left title-heading-tag sm-text-align-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.8;\">CALENDRIER<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#ffffff;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first fusion-animated\" style=\"--awb-padding-top:35px;--awb-padding-bottom:30px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-border-color:#f0f0f0;--awb-border-right:1px;--awb-border-style:solid;--awb-margin-top:0px;--awb-margin-bottom:0px;width:50%;width:calc(50% - ( ( 0px ) * 0.5 ) );margin-right: 0px;\" data-animationtype=\"fadeInUp\" data-animationduration=\"1.0\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: center; letter-spacing: 1px; margin: 0px;\"><span style=\"color: #ffaa06; font-size: 23px;\" data-fusion-font=\"true\">PRIX<\/span><\/p>\n<\/div><div class=\"fusion-title title fusion-title-7 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top:5px;--awb-margin-bottom:5px;\"><h3 class=\"title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:32;line-height:1.3;\"><span style=\"font-size: 24px;\" data-fusion-font=\"true\"><b>95\u20ac \/ 130\u20ac<\/b><\/span><\/h3><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last fusion-animated\" style=\"--awb-padding-top:35px;--awb-padding-bottom:30px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-border-color:#f0f0f0;--awb-border-right:1px;--awb-border-style:solid;--awb-margin-top:0px;--awb-margin-bottom:0px;width:50%;width:calc(50% - ( ( 0px ) * 0.5 ) );\" data-animationtype=\"fadeInUp\" data-animationduration=\"1.0\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: center; letter-spacing: 1px; margin: 0px;\"><span style=\"color: #ffaa06; font-size: 24px;\" data-fusion-font=\"true\">T\u00c9L\u00c9PHONE<\/span><\/p>\n<\/div><div class=\"fusion-title title fusion-title-8 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top:5px;--awb-margin-bottom:5px;\"><h3 class=\"title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:32;line-height:1.3;\"><div style=\"text-align: center;\"><b style=\"color: var(--h3_typography-color); font-family: var(--h3_typography-font-family); font-style: var(--h3_typography-font-style,normal); letter-spacing: var(--h3_typography-letter-spacing); font-size: 24px;\"><span style=\"font-size: 44px; line-height: 16px;\" data-fusion-font=\"true\">+<\/span>32 (60) 31 26 70<\/b><\/div><\/h3><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div id=\"inscription\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"reservation\"><\/div><div class=\"fusion-text fusion-text-3\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 60px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">R\u00c9SERVATION<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"inscriptions\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 fusion-flex-container fusion-parallax-fixed hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:7%;--awb-padding-bottom:11%;--awb-padding-left:251px;--awb-padding-top-small:0px;--awb-padding-right-small:10px;--awb-padding-bottom-small:280px;--awb-padding-left-small:10px;--awb-margin-top-small:0px;--awb-background-color:#060607;--awb-background-image:url(&quot;https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2022\/01\/kart-fun-trophy-sprint-scaled.jpg&quot;);--awb-background-size:cover;background-attachment:fixed;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-4\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 38px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">R\u00c9SERVATION<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:80px;--awb-padding-bottom:80px;--awb-background-color:rgba(255,255,255,0);\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-animated\" style=\"--awb-padding-top:40px;--awb-padding-right:40px;--awb-padding-bottom:41px;--awb-padding-left:40px;--awb-overflow:hidden;--awb-bg-color:#ffffff;--awb-bg-size:cover;--awb-box-shadow:0px 25px 20px 0px rgba(61,61,61,0.1);;--awb-border-color:#eaeaea;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:10px 10px 10px 10px;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationtype=\"fadeInRight\" data-animationduration=\"0.9\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><script data-jetpack-boost=\"ignore\" type=\"text\/javascript\" src=\"https:\/\/www.apex-timing.com\/gokarts\/javascript\/ax.iframe.js\"><\/script>\n\n<iframe class=\"axiframe\" width=\"100%\" data-src=\"https:\/\/www.apex-timing.com\/gokarts\/events_booking.php?center=150&categories=S2FydCBGdW4gVHJvcGh5IC0gU3ByaW50\"><\/iframe><style type=\"text\/css\">.fusion-faqs-wrapper #accordian-1 .fusion-panel { border-color:#e2e2e2; }.fusion-faqs-wrapper #accordian-1 .fusion-panel:hover{ border-color: #e2e2e2; }.fusion-accordian #accordian-1 .panel-title a .fa-fusion-box:before{ font-size: 16px;}.fusion-accordian #accordian-1 .panel-title a .fa-fusion-box{ color: #ffffff;}.fusion-accordian  #accordian-1 .panel-title a{font-family:\"Zilla Slab\";font-style:normal;font-weight:400;}.fusion-accordian  #accordian-1 .panel-title a:not(:hover){}.fusion-accordian  #accordian-1 .toggle-content{font-family:\"Montserrat\";font-style:normal;font-weight:400;}.fusion-accordian #accordian-1 .fa-fusion-box { background-color: #212934;border-color: #212934;}.fusion-accordian #accordian-1 .panel-title a:hover,.fusion-accordian #accordian-1 .panel-title a.hover { color: #e10707;}.fusion-faq-shortcode .fusion-accordian #accordian-1 .fusion-toggle-boxed-mode:hover .panel-title a { color: #e10707;}.fusion-accordian #accordian-1 .panel-title .active .fa-fusion-box,.fusion-accordian #accordian-1 .panel-title a:hover .fa-fusion-box,.fusion-accordian #accordian-1 .panel-title a.hover .fa-fusion-box { background-color: #e10707!important;border-color: #e10707!important;}<\/style><div class=\"fusion-faq-shortcode\" style=\"\"><div class=\"fusion-faqs-wrapper\"><div class=\"accordian fusion-accordian\"><div class=\"panel-group\" id=\"accordian-1\"><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-20016 aide-reservation-en-ligne facturation\"><span class=\"entry-title rich-snippet-hidden\">Obtenir une facture pour ma soci\u00e9t\u00e9<\/span><span class=\"updated rich-snippet-hidden\">2026-03-03T11:52:39+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-20016\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-20016\" href=\"#collapse-1-20016\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Obtenir une facture pour ma soci\u00e9t\u00e9<\/div><\/a><\/h4><\/div><div id=\"collapse-1-20016\" aria-labelledby=\"faq_1-20016\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;--awb-circlecolor:#e10707;--awb-circle-yes-font-size:14.08px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<h2>ATTENTION \u2013 Changement pour la facturation<\/h2>\n<p>Si vous souhaitez obtenir une facture, vous devez :<br \/>\nCompl\u00e9ter correctement toutes vos coordonn\u00e9es (nom, adresse, soci\u00e9t\u00e9)<br \/>\nDemander la facture lors de votre passage en caisse, AVANT la validation du ticket<br \/>\nAucune facture ne pourra \u00eatre \u00e9tablie apr\u00e8s validation et encaissement du ticket.<\/p>\n<\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-5\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 38px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">TIMING<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div id=\"inscription\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-11 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"timing\"><\/div><div class=\"fusion-text fusion-text-6\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 60px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">TIMING<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-12 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:80px;--awb-padding-bottom:80px;--awb-background-color:rgba(255,255,255,0);\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-animated\" style=\"--awb-padding-top:40px;--awb-padding-right:40px;--awb-padding-bottom:41px;--awb-padding-left:40px;--awb-overflow:hidden;--awb-bg-color:#ffffff;--awb-bg-size:cover;--awb-box-shadow:0px 25px 20px 0px rgba(61,61,61,0.1);;--awb-border-color:#eaeaea;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:10px 10px 10px 10px;--awb-margin-top:0px;\" data-animationtype=\"fadeInRight\" data-animationduration=\"0.9\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none fusion-no-medium-visibility\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"664\" height=\"733\" title=\"Capture d&rsquo;\u00e9cran 2026-01-18 135624\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?resize=664%2C733&#038;ssl=1\" alt class=\"img-responsive wp-image-21460\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?resize=11%2C12&amp;ssl=1 11w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?resize=200%2C221&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?resize=272%2C300&amp;ssl=1 272w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?resize=400%2C442&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?resize=600%2C662&amp;ssl=1 600w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/Capture-decran-2026-01-18-135624.png?fit=664%2C733&amp;ssl=1 664w\" sizes=\"(max-width: 1200px) 100vw, 664px\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-13 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"calendrier\"><\/div><div class=\"fusion-text fusion-text-7\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 60px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CALENDRIER<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-14 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"calendrier-m\"><\/div><div class=\"fusion-text fusion-text-8\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 38px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CALENDRIER<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-15 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-image:linear-gradient(180deg, #000000 58%,rgba(255,255,255,0) 100%);;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:80%;--awb-spacing-right-large:2.4%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.4%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?ssl=1\" target=\"_self\" aria-label=\"SPRINT 2026\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=212%2C300&#038;ssl=1\" alt class=\"img-responsive wp-image-21458\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=200%2C283&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=212%2C300&amp;ssl=1 212w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=400%2C566&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=600%2C849&amp;ssl=1 600w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=724%2C1024&amp;ssl=1 724w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=768%2C1086&amp;ssl=1 768w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=800%2C1131&amp;ssl=1 800w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=1086%2C1536&amp;ssl=1 1086w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?resize=1200%2C1697&amp;ssl=1 1200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/01\/SPRINT-2026.jpg?fit=1241%2C1755&amp;ssl=1 1241w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 1200px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"rules\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-16 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"regles\"><\/div><div class=\"fusion-text fusion-text-9\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 60px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">R\u00c8GLEMENT<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"rules\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-17 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-23 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"regles-m\"><\/div><div class=\"fusion-text fusion-text-10\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 38px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">R\u00c8GLEMENT<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-18 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-24 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-25 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first fusion-animated\" style=\"--awb-padding-bottom:40px;--awb-bg-blend:overlay;--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-right: 4%;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.6\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/Reg-KFT-Sprint-2026-Fr-v2.pdf\" target=\"_blank\" aria-label=\"POUSSOIR ROUGE FR\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"266\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=300%2C266&#038;ssl=1\" alt class=\"img-responsive wp-image-21526\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=200%2C177&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=300%2C266&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=400%2C355&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=600%2C532&amp;ssl=1 600w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=768%2C681&amp;ssl=1 768w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?resize=800%2C709&amp;ssl=1 800w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-ROUGE-FR.png?fit=880%2C780&amp;ssl=1 880w\" sizes=\"(max-width: 1200px) 100vw, 600px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-26 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last fusion-animated\" style=\"--awb-padding-bottom:40px;--awb-bg-blend:overlay;--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.6\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/Reg-KFT-Sprint-2026-N-v2.pdf\" target=\"_blank\" aria-label=\"POUSSOIR JAUNE NL\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"265\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=300%2C265&#038;ssl=1\" alt class=\"img-responsive wp-image-21525\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=200%2C176&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=300%2C265&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=400%2C353&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=600%2C529&amp;ssl=1 600w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=768%2C677&amp;ssl=1 768w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=800%2C706&amp;ssl=1 800w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?resize=1024%2C903&amp;ssl=1 1024w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/POUSSOIR-JAUNE-NL.png?fit=1059%2C934&amp;ssl=1 1059w\" sizes=\"(max-width: 1200px) 100vw, 600px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-27 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-19 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-28 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-menu-anchor\" id=\"resultats\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-11\"><h2 class=\"fusion-responsive-typography-calculated\" style=\"text-align: center; --fontsize: 40; line-height: 1.2;\" data-fontsize=\"40\" data-lineheight=\"48px\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 60px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">R\u00c9SULTATS<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div id=\"resultats\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-20 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-29 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:19px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"resultats-m\"><\/div><div class=\"fusion-text fusion-text-12\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 38px; line-height: 83px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">R\u00c9SULTATS<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-21 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:40px;--awb-padding-bottom:25px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-flex-end\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-30 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-spacing-right-large:11.52%;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-3d button-xlarge button-custom fusion-button-default button-2 fusion-button-span-no fusion-animated fusion-has-button-gradient\" style=\"--button_bevel_color:#048900;--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\" target=\"_self\" href=\"#CATEG1\"><i class=\"fa-trophy fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\">CAT\u00c9GORIE 1 SWS<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-31 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-spacing-right-large:11.52%;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-3d button-xlarge button-custom fusion-button-default button-3 fusion-button-span-no fusion-animated fusion-has-button-gradient\" style=\"--button_bevel_color:#048900;--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\" target=\"_self\" href=\"#CATEG2\"><i class=\"fa-trophy fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\">CAT\u00c9GORIE 2 SWS<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-32 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-spacing-right-large:11.52%;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-3d button-xlarge button-custom fusion-button-default button-4 fusion-button-span-no fusion-animated fusion-has-button-gradient\" style=\"--button_bevel_color:#048900;--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\" target=\"_self\" href=\"#CATEG3\"><i class=\"fa-trophy fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\">CAT\u00c9GORIE 3 SWS<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-33 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-spacing-right-large:11.52%;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-3d button-xlarge button-custom fusion-button-default button-5 fusion-button-span-no fusion-animated fusion-has-button-gradient\" style=\"--button_bevel_color:#048900;--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\" target=\"_self\" href=\"#CATEGJNR\"><i class=\"fa-trophy fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\">CAT\u00c9GORIE JUNIOR SWS<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-34 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-spacing-right-large:11.52%;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-3d button-xlarge button-custom fusion-button-default button-6 fusion-button-span-no fusion-animated fusion-has-button-gradient\" style=\"--button_bevel_color:#048900;--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\" target=\"_self\" href=\"#CATEGFUN\"><i class=\"fa-trophy fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\"> CAT\u00c9GORIE FUN<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-35 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-spacing-right-large:11.52%;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-3d button-xlarge button-custom fusion-button-default button-7 fusion-button-span-no fusion-animated fusion-has-button-gradient\" style=\"--button_bevel_color:#048900;--button_accent_color:#ffffff;--button_border_color:#048900;--button_accent_hover_color:#ffeded;--button_border_hover_color:#048900;--button_gradient_top_color:#14d500;--button_gradient_bottom_color:#14d500;--button_gradient_top_color_hover:#048900;--button_gradient_bottom_color_hover:#14d500;\" data-animationtype=\"fadeInLeft\" data-animationduration=\"0.3\" data-animationoffset=\"top-into-view\" target=\"_self\" href=\"#CATEGFUNLIGHT\"><i class=\"fa-trophy fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\">CAT\u00c9GORIE FUN LIGHT<\/span><\/a><\/div><\/div><\/div><\/div><\/div><div id=\"CATEG1\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-22 has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-36 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-13\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 40px; line-height: 63px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CAT\u00c9GORIE 1 &#8211; SWS<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-23 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-37 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-spacing-right-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\">\n<table id=\"tablepress-20\" class=\"tablepress tablepress-id-20\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">CLASSEMENT<\/th><th class=\"column-2\">NOM<\/th><th class=\"column-3\">POINTS<\/th><th class=\"column-4\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 1<\/th><th class=\"column-5\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 2<\/th><th class=\"column-6\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 3<\/th><th class=\"column-7\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 1<\/th><th class=\"column-8\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 2<\/th><th class=\"column-9\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 3<\/th><th class=\"column-10\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 1<\/th><th class=\"column-11\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 2<\/th><th class=\"column-12\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 3<\/th><th class=\"column-13\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 1<\/th><th class=\"column-14\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 2<\/th><th class=\"column-15\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 3<\/th><th class=\"column-16\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 1<\/th><th class=\"column-17\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 2<\/th><th class=\"column-18\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 3<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">DELVENNE Simon<\/td><td class=\"column-3\">847<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">60<\/td><td class=\"column-7\">57<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">60<\/td><td class=\"column-10\">53<\/td><td class=\"column-11\">60<\/td><td class=\"column-12\">52<\/td><td class=\"column-13\">60<\/td><td class=\"column-14\">57<\/td><td class=\"column-15\">57<\/td><td class=\"column-16\">47<\/td><td class=\"column-17\">57<\/td><td class=\"column-18\">52<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">GHIDI Ludwig<\/td><td class=\"column-3\">800<\/td><td class=\"column-4\">54<\/td><td class=\"column-5\">50<\/td><td class=\"column-6\">53<\/td><td class=\"column-7\">55<\/td><td class=\"column-8\">57<\/td><td class=\"column-9\">47<\/td><td class=\"column-10\">60<\/td><td class=\"column-11\">48<\/td><td class=\"column-12\">45<\/td><td class=\"column-13\">57<\/td><td class=\"column-14\">51<\/td><td class=\"column-15\">60<\/td><td class=\"column-16\">53<\/td><td class=\"column-17\">55<\/td><td class=\"column-18\">55<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">VAN DEYCK Ozan<\/td><td class=\"column-3\">799<\/td><td class=\"column-4\">52<\/td><td class=\"column-5\">54<\/td><td class=\"column-6\">51<\/td><td class=\"column-7\">52<\/td><td class=\"column-8\">54<\/td><td class=\"column-9\">54<\/td><td class=\"column-10\">57<\/td><td class=\"column-11\">53<\/td><td class=\"column-12\">60<\/td><td class=\"column-13\">51<\/td><td class=\"column-14\">49<\/td><td class=\"column-15\">54<\/td><td class=\"column-16\">55<\/td><td class=\"column-17\">49<\/td><td class=\"column-18\">54<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">DECAMPS Rony<\/td><td class=\"column-3\">785<\/td><td class=\"column-4\">44<\/td><td class=\"column-5\">52<\/td><td class=\"column-6\">42<\/td><td class=\"column-7\">54<\/td><td class=\"column-8\">53<\/td><td class=\"column-9\">52<\/td><td class=\"column-10\">50<\/td><td class=\"column-11\">54<\/td><td class=\"column-12\">57<\/td><td class=\"column-13\">53<\/td><td class=\"column-14\">60<\/td><td class=\"column-15\">53<\/td><td class=\"column-16\">54<\/td><td class=\"column-17\">50<\/td><td class=\"column-18\">57<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">ZINGONE Alessandro<\/td><td class=\"column-3\">747<\/td><td class=\"column-4\">41<\/td><td class=\"column-5\">49<\/td><td class=\"column-6\">48<\/td><td class=\"column-7\">49<\/td><td class=\"column-8\">49<\/td><td class=\"column-9\">55<\/td><td class=\"column-10\">43<\/td><td class=\"column-11\">50<\/td><td class=\"column-12\">51<\/td><td class=\"column-13\">55<\/td><td class=\"column-14\">54<\/td><td class=\"column-15\">52<\/td><td class=\"column-16\">46<\/td><td class=\"column-17\">52<\/td><td class=\"column-18\">53<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">DECAMPS Milan<\/td><td class=\"column-3\">727<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">43<\/td><td class=\"column-6\">49<\/td><td class=\"column-7\">50<\/td><td class=\"column-8\">52<\/td><td class=\"column-9\">57<\/td><td class=\"column-10\">51<\/td><td class=\"column-11\">52<\/td><td class=\"column-12\">50<\/td><td class=\"column-13\">45<\/td><td class=\"column-14\">53<\/td><td class=\"column-15\">51<\/td><td class=\"column-16\">48<\/td><td class=\"column-17\">30<\/td><td class=\"column-18\">47<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">BOILEAU Alexy<\/td><td class=\"column-3\">663<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">51<\/td><td class=\"column-6\">57<\/td><td class=\"column-7\">60<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">51<\/td><td class=\"column-10\">54<\/td><td class=\"column-11\">57<\/td><td class=\"column-12\">55<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">52<\/td><td class=\"column-17\">60<\/td><td class=\"column-18\">51<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">CAMMAERT Nathan<\/td><td class=\"column-3\">660<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">38<\/td><td class=\"column-6\">44<\/td><td class=\"column-7\">39<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">36<\/td><td class=\"column-10\">44<\/td><td class=\"column-11\">46<\/td><td class=\"column-12\">48<\/td><td class=\"column-13\">50<\/td><td class=\"column-14\">48<\/td><td class=\"column-15\">41<\/td><td class=\"column-16\">49<\/td><td class=\"column-17\">44<\/td><td class=\"column-18\">44<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">BROHEE Alex<\/td><td class=\"column-3\">599<\/td><td class=\"column-4\">27<\/td><td class=\"column-5\">31<\/td><td class=\"column-6\">36<\/td><td class=\"column-7\">42<\/td><td class=\"column-8\">43<\/td><td class=\"column-9\">45<\/td><td class=\"column-10\">38<\/td><td class=\"column-11\">45<\/td><td class=\"column-12\">47<\/td><td class=\"column-13\">47<\/td><td class=\"column-14\">37<\/td><td class=\"column-15\">34<\/td><td class=\"column-16\">39<\/td><td class=\"column-17\">43<\/td><td class=\"column-18\">45<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">CORBIAU Alain<\/td><td class=\"column-3\">598<\/td><td class=\"column-4\">53<\/td><td class=\"column-5\">48<\/td><td class=\"column-6\">54<\/td><td class=\"column-7\">44<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">46<\/td><td class=\"column-10\">55<\/td><td class=\"column-11\">55<\/td><td class=\"column-12\">53<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">45<\/td><td class=\"column-17\">47<\/td><td class=\"column-18\">48<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">ANDRE Kevin<\/td><td class=\"column-3\">575<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">48<\/td><td class=\"column-8\">48<\/td><td class=\"column-9\">48<\/td><td class=\"column-10\">49<\/td><td class=\"column-11\">49<\/td><td class=\"column-12\">54<\/td><td class=\"column-13\">54<\/td><td class=\"column-14\">43<\/td><td class=\"column-15\">48<\/td><td class=\"column-16\">42<\/td><td class=\"column-17\">46<\/td><td class=\"column-18\">46<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">KOCH Ethan<\/td><td class=\"column-3\">561<\/td><td class=\"column-4\">31<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">46<\/td><td class=\"column-7\">46<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">53<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">52<\/td><td class=\"column-14\">52<\/td><td class=\"column-15\">44<\/td><td class=\"column-16\">57<\/td><td class=\"column-17\">53<\/td><td class=\"column-18\">42<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">WINKEL Etienne<\/td><td class=\"column-3\">487<\/td><td class=\"column-4\">39<\/td><td class=\"column-5\">44<\/td><td class=\"column-6\">24<\/td><td class=\"column-7\">41<\/td><td class=\"column-8\">46<\/td><td class=\"column-9\">43<\/td><td class=\"column-10\">42<\/td><td class=\"column-11\">39<\/td><td class=\"column-12\">36<\/td><td class=\"column-13\">42<\/td><td class=\"column-14\">42<\/td><td class=\"column-15\">49<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">DI TIMOTEO Jeremy<\/td><td class=\"column-3\">456<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">36<\/td><td class=\"column-8\">40<\/td><td class=\"column-9\">33<\/td><td class=\"column-10\">41<\/td><td class=\"column-11\">43<\/td><td class=\"column-12\">40<\/td><td class=\"column-13\">38<\/td><td class=\"column-14\">39<\/td><td class=\"column-15\">38<\/td><td class=\"column-16\">34<\/td><td class=\"column-17\">40<\/td><td class=\"column-18\">34<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">CHAVEZ Valentin<\/td><td class=\"column-3\">450<\/td><td class=\"column-4\">29<\/td><td class=\"column-5\">33<\/td><td class=\"column-6\">33<\/td><td class=\"column-7\">38<\/td><td class=\"column-8\">35<\/td><td class=\"column-9\">40<\/td><td class=\"column-10\">46<\/td><td class=\"column-11\">38<\/td><td class=\"column-12\">44<\/td><td class=\"column-13\">36<\/td><td class=\"column-14\">38<\/td><td class=\"column-15\">40<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">BONIFAZIO Lorenzo<\/td><td class=\"column-3\">431<\/td><td class=\"column-4\">51<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">55<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">44<\/td><td class=\"column-14\">45<\/td><td class=\"column-15\">55<\/td><td class=\"column-16\">51<\/td><td class=\"column-17\">35<\/td><td class=\"column-18\">40<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">GAUDIO Alessandro<\/td><td class=\"column-3\">418<\/td><td class=\"column-4\">30<\/td><td class=\"column-5\">32<\/td><td class=\"column-6\">32<\/td><td class=\"column-7\">37<\/td><td class=\"column-8\">34<\/td><td class=\"column-9\">31<\/td><td class=\"column-10\">40<\/td><td class=\"column-11\">41<\/td><td class=\"column-12\">43<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">31<\/td><td class=\"column-17\">32<\/td><td class=\"column-18\">35<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">LANNI Claudio<\/td><td class=\"column-3\">415<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">46<\/td><td class=\"column-6\">50<\/td><td class=\"column-7\">35<\/td><td class=\"column-8\">41<\/td><td class=\"column-9\">50<\/td><td class=\"column-10\">47<\/td><td class=\"column-11\">51<\/td><td class=\"column-12\">49<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">LOTHAIRE Emilien<\/td><td class=\"column-3\">405<\/td><td class=\"column-4\">28<\/td><td class=\"column-5\">26<\/td><td class=\"column-6\">25<\/td><td class=\"column-7\">31<\/td><td class=\"column-8\">33<\/td><td class=\"column-9\">35<\/td><td class=\"column-10\">39<\/td><td class=\"column-11\">40<\/td><td class=\"column-12\">39<\/td><td class=\"column-13\">37<\/td><td class=\"column-14\">35<\/td><td class=\"column-15\">37<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">HUBERT Noah<\/td><td class=\"column-3\">397<\/td><td class=\"column-4\">57<\/td><td class=\"column-5\">57<\/td><td class=\"column-6\">52<\/td><td class=\"column-7\">43<\/td><td class=\"column-8\">39<\/td><td class=\"column-9\">31<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">38<\/td><td class=\"column-17\">41<\/td><td class=\"column-18\">39<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">COLETTE Maxence<\/td><td class=\"column-3\">375<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">45<\/td><td class=\"column-11\">44<\/td><td class=\"column-12\">42<\/td><td class=\"column-13\">40<\/td><td class=\"column-14\">46<\/td><td class=\"column-15\">39<\/td><td class=\"column-16\">43<\/td><td class=\"column-17\">38<\/td><td class=\"column-18\">38<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">PIRMEZ Theo<\/td><td class=\"column-3\">319<\/td><td class=\"column-4\">47<\/td><td class=\"column-5\">53<\/td><td class=\"column-6\">45<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">60<\/td><td class=\"column-17\">54<\/td><td class=\"column-18\">60<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">KOKKEN Kilian<\/td><td class=\"column-3\">296<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">49<\/td><td class=\"column-14\">50<\/td><td class=\"column-15\">50<\/td><td class=\"column-16\">50<\/td><td class=\"column-17\">48<\/td><td class=\"column-18\">49<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">BASTIN Thomas<\/td><td class=\"column-3\">279<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">53<\/td><td class=\"column-8\">51<\/td><td class=\"column-9\">39<\/td><td class=\"column-10\">48<\/td><td class=\"column-11\">42<\/td><td class=\"column-12\">46<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">HERTAULT Kevin<\/td><td class=\"column-3\">265<\/td><td class=\"column-4\">40<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">52<\/td><td class=\"column-11\">47<\/td><td class=\"column-12\">41<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">LALMAND Pierre<\/td><td class=\"column-3\">264<\/td><td class=\"column-4\">48<\/td><td class=\"column-5\">42<\/td><td class=\"column-6\">47<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">39<\/td><td class=\"column-14\">41<\/td><td class=\"column-15\">47<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">SZURPIT Adam<\/td><td class=\"column-3\">256<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">29<\/td><td class=\"column-6\">34<\/td><td class=\"column-7\">47<\/td><td class=\"column-8\">47<\/td><td class=\"column-9\">49<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">VANHALLE St\u00e9phane<\/td><td class=\"column-3\">255<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">43<\/td><td class=\"column-14\">40<\/td><td class=\"column-15\">43<\/td><td class=\"column-16\">41<\/td><td class=\"column-17\">45<\/td><td class=\"column-18\">43<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">MUSSO Giuseppe<\/td><td class=\"column-3\">236<\/td><td class=\"column-4\">32<\/td><td class=\"column-5\">35<\/td><td class=\"column-6\">38<\/td><td class=\"column-7\">51<\/td><td class=\"column-8\">38<\/td><td class=\"column-9\">42<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">SCHMITT YANICK<\/td><td class=\"column-3\">236<\/td><td class=\"column-4\">43<\/td><td class=\"column-5\">39<\/td><td class=\"column-6\">39<\/td><td class=\"column-7\">40<\/td><td class=\"column-8\">37<\/td><td class=\"column-9\">38<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">FIVET Nathan<\/td><td class=\"column-3\">234<\/td><td class=\"column-4\">42<\/td><td class=\"column-5\">47<\/td><td class=\"column-6\">43<\/td><td class=\"column-7\">33<\/td><td class=\"column-8\">32<\/td><td class=\"column-9\">37<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\">CUIGNEZ Kevin<\/td><td class=\"column-3\">231<\/td><td class=\"column-4\">35<\/td><td class=\"column-5\">36<\/td><td class=\"column-6\">29<\/td><td class=\"column-7\">45<\/td><td class=\"column-8\">42<\/td><td class=\"column-9\">44<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">33<\/td><td class=\"column-2\">STARKOV Sergii<\/td><td class=\"column-3\">202<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">32<\/td><td class=\"column-8\">31<\/td><td class=\"column-9\">34<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">35<\/td><td class=\"column-17\">37<\/td><td class=\"column-18\">33<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">DEBAISIEUX Guillaume<\/td><td class=\"column-3\">188<\/td><td class=\"column-4\">25<\/td><td class=\"column-5\">30<\/td><td class=\"column-6\">31<\/td><td class=\"column-7\">34<\/td><td class=\"column-8\">36<\/td><td class=\"column-9\">32<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">35<\/td><td class=\"column-2\">GOLARD Emy<\/td><td class=\"column-3\">149<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">48<\/td><td class=\"column-14\">55<\/td><td class=\"column-15\">46<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">LEENDERS Maxime<\/td><td class=\"column-3\">145<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">44<\/td><td class=\"column-17\">51<\/td><td class=\"column-18\">50<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">37<\/td><td class=\"column-2\">GENTILE Gianni<\/td><td class=\"column-3\">138<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">46<\/td><td class=\"column-14\">47<\/td><td class=\"column-15\">45<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">HEYVAERT Yonas<\/td><td class=\"column-3\">127<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">41<\/td><td class=\"column-14\">44<\/td><td class=\"column-15\">42<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">39<\/td><td class=\"column-2\">SURKIJN Emilien<\/td><td class=\"column-3\">120<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">37<\/td><td class=\"column-17\">42<\/td><td class=\"column-18\">41<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">HAMMOU Brahim<\/td><td class=\"column-3\">113<\/td><td class=\"column-4\">38<\/td><td class=\"column-5\">34<\/td><td class=\"column-6\">41<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">41<\/td><td class=\"column-2\">DE PAUW Arne<\/td><td class=\"column-3\">111<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">36<\/td><td class=\"column-11\">37<\/td><td class=\"column-12\">38<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">MINICHELLO Salvatore<\/td><td class=\"column-3\">111<\/td><td class=\"column-4\">37<\/td><td class=\"column-5\">37<\/td><td class=\"column-6\">37<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">43<\/td><td class=\"column-2\">GRAM Nathan<\/td><td class=\"column-3\">110<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">37<\/td><td class=\"column-11\">36<\/td><td class=\"column-12\">37<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">44<\/td><td class=\"column-2\">ANDRE Maxime<\/td><td class=\"column-3\">109<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">40<\/td><td class=\"column-17\">39<\/td><td class=\"column-18\">30<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">KUYPERS Florian<\/td><td class=\"column-3\">109<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">36<\/td><td class=\"column-17\">36<\/td><td class=\"column-18\">37<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">46<\/td><td class=\"column-2\">DARMON Esteban<\/td><td class=\"column-3\">106<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">34<\/td><td class=\"column-14\">36<\/td><td class=\"column-15\">36<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">47<\/td><td class=\"column-2\">PEDRAZZOLI Tanguy<\/td><td class=\"column-3\">104<\/td><td class=\"column-4\">33<\/td><td class=\"column-5\">41<\/td><td class=\"column-6\">30<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">JOZEFIAK Aleaxandre<\/td><td class=\"column-3\">104<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">35<\/td><td class=\"column-14\">34<\/td><td class=\"column-15\">35<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">49<\/td><td class=\"column-2\">DURIEUX Marc<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">30<\/td><td class=\"column-17\">34<\/td><td class=\"column-18\">36<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\">TYTENS Gregory<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">33<\/td><td class=\"column-17\">33<\/td><td class=\"column-18\">32<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">51<\/td><td class=\"column-2\">VERHEYDEN Arno<\/td><td class=\"column-3\">94<\/td><td class=\"column-4\">36<\/td><td class=\"column-5\">23<\/td><td class=\"column-6\">35<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">MARTIN Anael<\/td><td class=\"column-3\">94<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">32<\/td><td class=\"column-17\">31<\/td><td class=\"column-18\">31<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">53<\/td><td class=\"column-2\">DERYCKERE Robby<\/td><td class=\"column-3\">88<\/td><td class=\"column-4\">34<\/td><td class=\"column-5\">27<\/td><td class=\"column-6\">27<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">54<\/td><td class=\"column-2\">SALUCCI Fabrizio<\/td><td class=\"column-3\">82<\/td><td class=\"column-4\">26<\/td><td class=\"column-5\">28<\/td><td class=\"column-6\">28<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\">DE WANDEL Tom<\/td><td class=\"column-3\">74<\/td><td class=\"column-4\">24<\/td><td class=\"column-5\">24<\/td><td class=\"column-6\">26<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">56<\/td><td class=\"column-2\">BARBE Gaetan<\/td><td class=\"column-3\">71<\/td><td class=\"column-4\">23<\/td><td class=\"column-5\">25<\/td><td class=\"column-6\">23<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">57<\/td><td class=\"column-2\">DE VILDER Robbe<\/td><td class=\"column-3\">22<\/td><td class=\"column-4\">22<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-20 from cache --><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-24 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-38 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-large-visibility\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-5 hover-type-none fusion-no-large-visibility\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/2026-KFT-SPRINT-CAT1-general.pdf\" target=\"_blank\" aria-label=\"Image4\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"261\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image4.png?resize=300%2C261&#038;ssl=1\" alt class=\"img-responsive wp-image-21552\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image4.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image4.png?resize=200%2C174&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image4.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image4.png?resize=400%2C349&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image4.png?fit=584%2C509&amp;ssl=1 584w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 300px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"CATEG2\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-25 has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-39 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-14\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 40px; line-height: 63px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CAT\u00c9GORIE 2 &#8211; SWS<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-26 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-40 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-spacing-right-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\">\n<table id=\"tablepress-21\" class=\"tablepress tablepress-id-21\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">NOM<\/th><th class=\"column-3\">POINTS<\/th><th class=\"column-4\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 1<\/th><th class=\"column-5\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 2<\/th><th class=\"column-6\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 3<\/th><th class=\"column-7\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 1<\/th><th class=\"column-8\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 2<\/th><th class=\"column-9\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 3<\/th><th class=\"column-10\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 1<\/th><th class=\"column-11\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 2<\/th><th class=\"column-12\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 3<\/th><th class=\"column-13\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 2<\/th><th class=\"column-14\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 1<\/th><th class=\"column-15\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 3<\/th><th class=\"column-16\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 1<\/th><th class=\"column-17\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 2<\/th><th class=\"column-18\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 3<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">GHIDI Ludwig<\/td><td class=\"column-3\">833<\/td><td class=\"column-4\">57<\/td><td class=\"column-5\">52<\/td><td class=\"column-6\">55<\/td><td class=\"column-7\">60<\/td><td class=\"column-8\">57<\/td><td class=\"column-9\">55<\/td><td class=\"column-10\">60<\/td><td class=\"column-11\">53<\/td><td class=\"column-12\">53<\/td><td class=\"column-13\">52<\/td><td class=\"column-14\">49<\/td><td class=\"column-15\">53<\/td><td class=\"column-16\">60<\/td><td class=\"column-17\">60<\/td><td class=\"column-18\">57<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">DECAMPS Milan<\/td><td class=\"column-3\">808<\/td><td class=\"column-4\">54<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">54<\/td><td class=\"column-7\">54<\/td><td class=\"column-8\">52<\/td><td class=\"column-9\">54<\/td><td class=\"column-10\">50<\/td><td class=\"column-11\">55<\/td><td class=\"column-12\">50<\/td><td class=\"column-13\">53<\/td><td class=\"column-14\">52<\/td><td class=\"column-15\">60<\/td><td class=\"column-16\">55<\/td><td class=\"column-17\">57<\/td><td class=\"column-18\">53<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">DE VILLE DE GOYET Mattys<\/td><td class=\"column-3\">779<\/td><td class=\"column-4\">53<\/td><td class=\"column-5\">42<\/td><td class=\"column-6\">51<\/td><td class=\"column-7\">53<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">53<\/td><td class=\"column-10\">49<\/td><td class=\"column-11\">51<\/td><td class=\"column-12\">51<\/td><td class=\"column-13\">57<\/td><td class=\"column-14\">60<\/td><td class=\"column-15\">57<\/td><td class=\"column-16\">52<\/td><td class=\"column-17\">49<\/td><td class=\"column-18\">51<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">MARIA Salvatore<\/td><td class=\"column-3\">768<\/td><td class=\"column-4\">52<\/td><td class=\"column-5\">29<\/td><td class=\"column-6\">29<\/td><td class=\"column-7\">55<\/td><td class=\"column-8\">54<\/td><td class=\"column-9\">60<\/td><td class=\"column-10\">52<\/td><td class=\"column-11\">57<\/td><td class=\"column-12\">55<\/td><td class=\"column-13\">60<\/td><td class=\"column-14\">54<\/td><td class=\"column-15\">54<\/td><td class=\"column-16\">48<\/td><td class=\"column-17\">54<\/td><td class=\"column-18\">55<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">DECAMPS Rony<\/td><td class=\"column-3\">727<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">50<\/td><td class=\"column-6\">48<\/td><td class=\"column-7\">46<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">45<\/td><td class=\"column-10\">46<\/td><td class=\"column-11\">48<\/td><td class=\"column-12\">49<\/td><td class=\"column-13\">49<\/td><td class=\"column-14\">47<\/td><td class=\"column-15\">52<\/td><td class=\"column-16\">57<\/td><td class=\"column-17\">50<\/td><td class=\"column-18\">50<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">GIA Luca<\/td><td class=\"column-3\">705<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">53<\/td><td class=\"column-6\">52<\/td><td class=\"column-7\">37<\/td><td class=\"column-8\">46<\/td><td class=\"column-9\">46<\/td><td class=\"column-10\">48<\/td><td class=\"column-11\">47<\/td><td class=\"column-12\">48<\/td><td class=\"column-13\">45<\/td><td class=\"column-14\">48<\/td><td class=\"column-15\">47<\/td><td class=\"column-16\">47<\/td><td class=\"column-17\">44<\/td><td class=\"column-18\">48<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">LIBERT Louis<\/td><td class=\"column-3\">677<\/td><td class=\"column-4\">51<\/td><td class=\"column-5\">51<\/td><td class=\"column-6\">50<\/td><td class=\"column-7\">38<\/td><td class=\"column-8\">47<\/td><td class=\"column-9\">48<\/td><td class=\"column-10\">41<\/td><td class=\"column-11\">46<\/td><td class=\"column-12\">41<\/td><td class=\"column-13\">42<\/td><td class=\"column-14\">40<\/td><td class=\"column-15\">44<\/td><td class=\"column-16\">46<\/td><td class=\"column-17\">46<\/td><td class=\"column-18\">46<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">CORBIAU Alain<\/td><td class=\"column-3\">659<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">60<\/td><td class=\"column-7\">52<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">57<\/td><td class=\"column-10\">51<\/td><td class=\"column-11\">60<\/td><td class=\"column-12\">52<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">53<\/td><td class=\"column-17\">52<\/td><td class=\"column-18\">52<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">LEMMENS Simon<\/td><td class=\"column-3\">635<\/td><td class=\"column-4\">39<\/td><td class=\"column-5\">37<\/td><td class=\"column-6\">42<\/td><td class=\"column-7\">48<\/td><td class=\"column-8\">37<\/td><td class=\"column-9\">31<\/td><td class=\"column-10\">47<\/td><td class=\"column-11\">42<\/td><td class=\"column-12\">46<\/td><td class=\"column-13\">39<\/td><td class=\"column-14\">41<\/td><td class=\"column-15\">49<\/td><td class=\"column-16\">45<\/td><td class=\"column-17\">47<\/td><td class=\"column-18\">45<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">WARNIER Nicolas<\/td><td class=\"column-3\">625<\/td><td class=\"column-4\">43<\/td><td class=\"column-5\">48<\/td><td class=\"column-6\">53<\/td><td class=\"column-7\">57<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">50<\/td><td class=\"column-10\">54<\/td><td class=\"column-11\">49<\/td><td class=\"column-12\">54<\/td><td class=\"column-13\">54<\/td><td class=\"column-14\">55<\/td><td class=\"column-15\">48<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">RICCARDI Noah<\/td><td class=\"column-3\">610<\/td><td class=\"column-4\">42<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">30<\/td><td class=\"column-7\">39<\/td><td class=\"column-8\">39<\/td><td class=\"column-9\">30<\/td><td class=\"column-10\">43<\/td><td class=\"column-11\">44<\/td><td class=\"column-12\">42<\/td><td class=\"column-13\">43<\/td><td class=\"column-14\">42<\/td><td class=\"column-15\">50<\/td><td class=\"column-16\">42<\/td><td class=\"column-17\">43<\/td><td class=\"column-18\">41<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">DI TIMOTEO Jeremy<\/td><td class=\"column-3\">543<\/td><td class=\"column-4\">28<\/td><td class=\"column-5\">30<\/td><td class=\"column-6\">36<\/td><td class=\"column-7\">35<\/td><td class=\"column-8\">33<\/td><td class=\"column-9\">44<\/td><td class=\"column-10\">45<\/td><td class=\"column-11\">40<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">41<\/td><td class=\"column-14\">44<\/td><td class=\"column-15\">41<\/td><td class=\"column-16\">43<\/td><td class=\"column-17\">39<\/td><td class=\"column-18\">44<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">RANALLO Alesandro<\/td><td class=\"column-3\">499<\/td><td class=\"column-4\">37<\/td><td class=\"column-5\">47<\/td><td class=\"column-6\">44<\/td><td class=\"column-7\">50<\/td><td class=\"column-8\">51<\/td><td class=\"column-9\">52<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">39<\/td><td class=\"column-12\">38<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">44<\/td><td class=\"column-17\">48<\/td><td class=\"column-18\">49<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">DURIEUX Marc<\/td><td class=\"column-3\">465<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">49<\/td><td class=\"column-6\">33<\/td><td class=\"column-7\">42<\/td><td class=\"column-8\">34<\/td><td class=\"column-9\">35<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">43<\/td><td class=\"column-12\">43<\/td><td class=\"column-13\">50<\/td><td class=\"column-14\">45<\/td><td class=\"column-15\">46<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">CICCHELLERO Quentin<\/td><td class=\"column-3\">360<\/td><td class=\"column-4\">33<\/td><td class=\"column-5\">34<\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">41<\/td><td class=\"column-8\">30<\/td><td class=\"column-9\">41<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">49<\/td><td class=\"column-17\">45<\/td><td class=\"column-18\">47<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">KINNEN Cyril<\/td><td class=\"column-3\">360<\/td><td class=\"column-4\">32<\/td><td class=\"column-5\">33<\/td><td class=\"column-6\">47<\/td><td class=\"column-7\">45<\/td><td class=\"column-8\">36<\/td><td class=\"column-9\">42<\/td><td class=\"column-10\">44<\/td><td class=\"column-11\">37<\/td><td class=\"column-12\">44<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">LECOCQ Adam<\/td><td class=\"column-3\">320<\/td><td class=\"column-4\">29<\/td><td class=\"column-5\">31<\/td><td class=\"column-6\">34<\/td><td class=\"column-7\">32<\/td><td class=\"column-8\">31<\/td><td class=\"column-9\">36<\/td><td class=\"column-10\">42<\/td><td class=\"column-11\">45<\/td><td class=\"column-12\">40<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">LEBRUN Victoria<\/td><td class=\"column-3\">319<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">55<\/td><td class=\"column-11\">54<\/td><td class=\"column-12\">47<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">50<\/td><td class=\"column-17\">53<\/td><td class=\"column-18\">60<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">GALICHET Geoffroy<\/td><td class=\"column-3\">303<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">38<\/td><td class=\"column-14\">51<\/td><td class=\"column-15\">51<\/td><td class=\"column-16\">54<\/td><td class=\"column-17\">55<\/td><td class=\"column-18\">54<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">ANDRE Kevin<\/td><td class=\"column-3\">298<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">53<\/td><td class=\"column-11\">50<\/td><td class=\"column-12\">60<\/td><td class=\"column-13\">46<\/td><td class=\"column-14\">46<\/td><td class=\"column-15\">43<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">SCHMITT YANICK<\/td><td class=\"column-3\">286<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">57<\/td><td class=\"column-6\">46<\/td><td class=\"column-7\">44<\/td><td class=\"column-8\">42<\/td><td class=\"column-9\">47<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">PETRONIN Thibault<\/td><td class=\"column-3\">284<\/td><td class=\"column-4\">44<\/td><td class=\"column-5\">46<\/td><td class=\"column-6\">39<\/td><td class=\"column-7\">51<\/td><td class=\"column-8\">53<\/td><td class=\"column-9\">51<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">PINEUX Arnaud<\/td><td class=\"column-3\">266<\/td><td class=\"column-4\">31<\/td><td class=\"column-5\">39<\/td><td class=\"column-6\">49<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">48<\/td><td class=\"column-14\">57<\/td><td class=\"column-15\">42<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">ROBAUX Gr\u00e9gory<\/td><td class=\"column-3\">266<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">51<\/td><td class=\"column-14\">50<\/td><td class=\"column-15\">35<\/td><td class=\"column-16\">51<\/td><td class=\"column-17\">37<\/td><td class=\"column-18\">42<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">DE BRAUWER Theo<\/td><td class=\"column-3\">257<\/td><td class=\"column-4\">35<\/td><td class=\"column-5\">38<\/td><td class=\"column-6\">38<\/td><td class=\"column-7\">49<\/td><td class=\"column-8\">48<\/td><td class=\"column-9\">49<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">MASSART Julien<\/td><td class=\"column-3\">257<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">40<\/td><td class=\"column-11\">41<\/td><td class=\"column-12\">45<\/td><td class=\"column-13\">47<\/td><td class=\"column-14\">39<\/td><td class=\"column-15\">45<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">LANNI Claudio<\/td><td class=\"column-3\">252<\/td><td class=\"column-4\">47<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\">45<\/td><td class=\"column-7\">36<\/td><td class=\"column-8\">40<\/td><td class=\"column-9\">39<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">MUSSO Giuseppe<\/td><td class=\"column-3\">248<\/td><td class=\"column-4\">48<\/td><td class=\"column-5\">32<\/td><td class=\"column-6\">35<\/td><td class=\"column-7\">47<\/td><td class=\"column-8\">43<\/td><td class=\"column-9\">43<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">SOBKOWIAK Noa<\/td><td class=\"column-3\">248<\/td><td class=\"column-4\">38<\/td><td class=\"column-5\">44<\/td><td class=\"column-6\">43<\/td><td class=\"column-7\">40<\/td><td class=\"column-8\">49<\/td><td class=\"column-9\">34<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">CUIGNEZ Kevin<\/td><td class=\"column-3\">228<\/td><td class=\"column-4\">40<\/td><td class=\"column-5\">41<\/td><td class=\"column-6\">28<\/td><td class=\"column-7\">43<\/td><td class=\"column-8\">38<\/td><td class=\"column-9\">38<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">COGGHE Roman<\/td><td class=\"column-3\">226<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">39<\/td><td class=\"column-11\">38<\/td><td class=\"column-12\">39<\/td><td class=\"column-13\">36<\/td><td class=\"column-14\">37<\/td><td class=\"column-15\">37<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\">LOGRILLO Vito Giacomo<\/td><td class=\"column-3\">212<\/td><td class=\"column-4\">30<\/td><td class=\"column-5\">28<\/td><td class=\"column-6\">31<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">44<\/td><td class=\"column-14\">43<\/td><td class=\"column-15\">36<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">SPOTO  Francesco<\/td><td class=\"column-3\">212<\/td><td class=\"column-4\">34<\/td><td class=\"column-5\">36<\/td><td class=\"column-6\">41<\/td><td class=\"column-7\">33<\/td><td class=\"column-8\">35<\/td><td class=\"column-9\">33<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">MUSSO Lenzo<\/td><td class=\"column-3\">171<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">54<\/td><td class=\"column-6\">57<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">35<\/td><td class=\"column-2\">BOILEAU Alexy<\/td><td class=\"column-3\">166<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">57<\/td><td class=\"column-11\">52<\/td><td class=\"column-12\">57<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">KOKKEN Kilian<\/td><td class=\"column-3\">163<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">55<\/td><td class=\"column-14\">53<\/td><td class=\"column-15\">55<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">37<\/td><td class=\"column-2\">LALMAND Pierre<\/td><td class=\"column-3\">131<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">37<\/td><td class=\"column-17\">51<\/td><td class=\"column-18\">43<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">STARKOV Sergii<\/td><td class=\"column-3\">121<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">39<\/td><td class=\"column-17\">42<\/td><td class=\"column-18\">40<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">HANSE Renaud<\/td><td class=\"column-3\">121<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">41<\/td><td class=\"column-17\">41<\/td><td class=\"column-18\">39<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">ESPERT Matt<\/td><td class=\"column-3\">118<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">40<\/td><td class=\"column-17\">40<\/td><td class=\"column-18\">38<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">41<\/td><td class=\"column-2\">MEBUS Milko<\/td><td class=\"column-3\">116<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">40<\/td><td class=\"column-14\">36<\/td><td class=\"column-15\">40<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">42<\/td><td class=\"column-2\">HAMMOU Brahim<\/td><td class=\"column-3\">115<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">30<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">40<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">43<\/td><td class=\"column-2\">ISTACE Loan<\/td><td class=\"column-3\">114<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">37<\/td><td class=\"column-14\">38<\/td><td class=\"column-15\">39<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">44<\/td><td class=\"column-2\">LEGNAME Danilo<\/td><td class=\"column-3\">113<\/td><td class=\"column-4\">41<\/td><td class=\"column-5\">35<\/td><td class=\"column-6\">37<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">WEYDISCH Thibaut<\/td><td class=\"column-3\">113<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">38<\/td><td class=\"column-17\">38<\/td><td class=\"column-18\">37<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">46<\/td><td class=\"column-2\">EBBENI Julien<\/td><td class=\"column-3\">112<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">34<\/td><td class=\"column-8\">41<\/td><td class=\"column-9\">37<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">47<\/td><td class=\"column-2\">ALEXANDER Sels<\/td><td class=\"column-3\">111<\/td><td class=\"column-4\">36<\/td><td class=\"column-5\">43<\/td><td class=\"column-6\">32<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">48<\/td><td class=\"column-2\">DE STEFANO Romano<\/td><td class=\"column-3\">108<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">35<\/td><td class=\"column-14\">35<\/td><td class=\"column-15\">38<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">49<\/td><td class=\"column-2\">MAAFI Antoine<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">31<\/td><td class=\"column-8\">32<\/td><td class=\"column-9\">32<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-21 from cache --><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-27 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-41 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-large-visibility\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-6 hover-type-none fusion-no-large-visibility\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/2026-KFT-SPRINT-CAT2-general.pdf\" target=\"_blank\" aria-label=\"Image5\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"261\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image5.png?resize=300%2C261&#038;ssl=1\" alt class=\"img-responsive wp-image-21553\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image5.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image5.png?resize=200%2C174&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image5.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image5.png?resize=400%2C349&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image5.png?fit=584%2C509&amp;ssl=1 584w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 300px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"CATEG3\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-28 has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-42 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-15\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 40px; line-height: 63px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CAT\u00c9GORIE 3 &#8211; SWS<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-29 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-43 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-spacing-right-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\">\n<table id=\"tablepress-22\" class=\"tablepress tablepress-id-22\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">NOM<\/th><th class=\"column-3\">POINTS<\/th><th class=\"column-4\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 1<\/th><th class=\"column-5\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 2<\/th><th class=\"column-6\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 3<\/th><th class=\"column-7\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 1<\/th><th class=\"column-8\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 2<\/th><th class=\"column-9\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 3<\/th><th class=\"column-10\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 1<\/th><th class=\"column-11\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 2<\/th><th class=\"column-12\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 3<\/th><th class=\"column-13\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 1<\/th><th class=\"column-14\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 2<\/th><th class=\"column-15\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 3<\/th><th class=\"column-16\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 1<\/th><th class=\"column-17\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 2<\/th><th class=\"column-18\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 3<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">PIETTE Arthur<\/td><td class=\"column-3\">809<\/td><td class=\"column-4\">57<\/td><td class=\"column-5\">57<\/td><td class=\"column-6\">54<\/td><td class=\"column-7\">48<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">54<\/td><td class=\"column-10\">60<\/td><td class=\"column-11\">53<\/td><td class=\"column-12\">51<\/td><td class=\"column-13\">55<\/td><td class=\"column-14\">55<\/td><td class=\"column-15\">54<\/td><td class=\"column-16\">53<\/td><td class=\"column-17\">51<\/td><td class=\"column-18\">52<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">KOKKEN Kilian<\/td><td class=\"column-3\">806<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">49<\/td><td class=\"column-6\">51<\/td><td class=\"column-7\">51<\/td><td class=\"column-8\">54<\/td><td class=\"column-9\">57<\/td><td class=\"column-10\">55<\/td><td class=\"column-11\">60<\/td><td class=\"column-12\">54<\/td><td class=\"column-13\">54<\/td><td class=\"column-14\">52<\/td><td class=\"column-15\">55<\/td><td class=\"column-16\">55<\/td><td class=\"column-17\">55<\/td><td class=\"column-18\">55<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">DE VILLE DE GOYET Mattys<\/td><td class=\"column-3\">785<\/td><td class=\"column-4\">51<\/td><td class=\"column-5\">51<\/td><td class=\"column-6\">53<\/td><td class=\"column-7\">50<\/td><td class=\"column-8\">57<\/td><td class=\"column-9\">52<\/td><td class=\"column-10\">52<\/td><td class=\"column-11\">54<\/td><td class=\"column-12\">56<\/td><td class=\"column-13\">51<\/td><td class=\"column-14\">49<\/td><td class=\"column-15\">51<\/td><td class=\"column-16\">51<\/td><td class=\"column-17\">53<\/td><td class=\"column-18\">54<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">VAN DOOSSELAER Julius<\/td><td class=\"column-3\">768<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">54<\/td><td class=\"column-6\">47<\/td><td class=\"column-7\">54<\/td><td class=\"column-8\">47<\/td><td class=\"column-9\">47<\/td><td class=\"column-10\">53<\/td><td class=\"column-11\">52<\/td><td class=\"column-12\">53<\/td><td class=\"column-13\">49<\/td><td class=\"column-14\">51<\/td><td class=\"column-15\">49<\/td><td class=\"column-16\">52<\/td><td class=\"column-17\">52<\/td><td class=\"column-18\">53<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">LAMOLINE Giuseppe<\/td><td class=\"column-3\">698<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">60<\/td><td class=\"column-7\">60<\/td><td class=\"column-8\">43<\/td><td class=\"column-9\">55<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">60<\/td><td class=\"column-14\">60<\/td><td class=\"column-15\">60<\/td><td class=\"column-16\">60<\/td><td class=\"column-17\">60<\/td><td class=\"column-18\">60<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">KOCH Ethan<\/td><td class=\"column-3\">680<\/td><td class=\"column-4\">54<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">55<\/td><td class=\"column-7\">57<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">60<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">57<\/td><td class=\"column-14\">57<\/td><td class=\"column-15\">57<\/td><td class=\"column-16\">54<\/td><td class=\"column-17\">57<\/td><td class=\"column-18\">57<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">LEBRUN Victoria<\/td><td class=\"column-3\">655<\/td><td class=\"column-4\">53<\/td><td class=\"column-5\">53<\/td><td class=\"column-6\">57<\/td><td class=\"column-7\">55<\/td><td class=\"column-8\">53<\/td><td class=\"column-9\">53<\/td><td class=\"column-10\">57<\/td><td class=\"column-11\">55<\/td><td class=\"column-12\">57<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">57<\/td><td class=\"column-17\">54<\/td><td class=\"column-18\">51<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">VOLCKAERTS Kyle<\/td><td class=\"column-3\">608<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">48<\/td><td class=\"column-6\">50<\/td><td class=\"column-7\">53<\/td><td class=\"column-8\">52<\/td><td class=\"column-9\">46<\/td><td class=\"column-10\">51<\/td><td class=\"column-11\">51<\/td><td class=\"column-12\">52<\/td><td class=\"column-13\">50<\/td><td class=\"column-14\">53<\/td><td class=\"column-15\">52<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">KOKKEN Alexia<\/td><td class=\"column-3\">442<\/td><td class=\"column-4\">48<\/td><td class=\"column-5\">50<\/td><td class=\"column-6\">49<\/td><td class=\"column-7\">46<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">50<\/td><td class=\"column-10\">49<\/td><td class=\"column-11\">50<\/td><td class=\"column-12\">50<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">LOGRILLO Vito Giacomo<\/td><td class=\"column-3\">429<\/td><td class=\"column-4\">47<\/td><td class=\"column-5\">47<\/td><td class=\"column-6\">48<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">47<\/td><td class=\"column-11\">48<\/td><td class=\"column-12\">48<\/td><td class=\"column-13\">48<\/td><td class=\"column-14\">48<\/td><td class=\"column-15\">48<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">QUEST Zephyr<\/td><td class=\"column-3\">322<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">49<\/td><td class=\"column-8\">51<\/td><td class=\"column-9\">51<\/td><td class=\"column-10\">54<\/td><td class=\"column-11\">57<\/td><td class=\"column-12\">60<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">FRANQUET Loris<\/td><td class=\"column-3\">301<\/td><td class=\"column-4\">52<\/td><td class=\"column-5\">52<\/td><td class=\"column-6\">52<\/td><td class=\"column-7\">47<\/td><td class=\"column-8\">49<\/td><td class=\"column-9\">49<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">QUEST Celeste<\/td><td class=\"column-3\">284<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">45<\/td><td class=\"column-8\">46<\/td><td class=\"column-9\">45<\/td><td class=\"column-10\">50<\/td><td class=\"column-11\">49<\/td><td class=\"column-12\">49<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">MIGLIONICO Mauro<\/td><td class=\"column-3\">270<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">46<\/td><td class=\"column-6\">46<\/td><td class=\"column-7\">44<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">44<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">JACQUES Dorian<\/td><td class=\"column-3\">159<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">52<\/td><td class=\"column-14\">54<\/td><td class=\"column-15\">53<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">DE CRAWHEZ Th\u00e9odore<\/td><td class=\"column-3\">153<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">53<\/td><td class=\"column-14\">50<\/td><td class=\"column-15\">50<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">DE BRAUWER Theo<\/td><td class=\"column-3\">148<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">52<\/td><td class=\"column-8\">48<\/td><td class=\"column-9\">48<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">CATHERINE Pascal<\/td><td class=\"column-3\">142<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">48<\/td><td class=\"column-11\">47<\/td><td class=\"column-12\">47<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">DE CRAWHEZ Elise<\/td><td class=\"column-3\">141<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">47<\/td><td class=\"column-14\">47<\/td><td class=\"column-15\">47<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">DE CRAWHEZ Raymond<\/td><td class=\"column-3\">138<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">46<\/td><td class=\"column-14\">46<\/td><td class=\"column-15\">46<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">ISTASSE Loan<\/td><td class=\"column-3\">135<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\">45<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">DE BRAUWER Kylian<\/td><td class=\"column-3\">131<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">43<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">43<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-22 from cache --><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-30 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-44 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-large-visibility\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-7 hover-type-none fusion-no-large-visibility\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/2026-KFT-SPRINT-CAT3-GENERAL.pdf\" target=\"_blank\" aria-label=\"Image6\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"261\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image6.png?resize=300%2C261&#038;ssl=1\" alt class=\"img-responsive wp-image-21554\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image6.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image6.png?resize=200%2C174&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image6.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image6.png?resize=400%2C348&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image6.png?fit=585%2C509&amp;ssl=1 585w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 300px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"CATEGJNR\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-31 has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-45 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-16\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 40px; line-height: 63px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CAT\u00c9GORIE JUNIOR &#8211; SWS<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-32 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-46 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-spacing-right-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\">\n<table id=\"tablepress-25\" class=\"tablepress tablepress-id-25\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">NOM<\/th><th class=\"column-3\">POINTS<\/th><th class=\"column-4\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 1<\/th><th class=\"column-5\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 2<\/th><th class=\"column-6\">ROUND 1<br \/>\n15-f\u00e9vr<br \/>\nRACE 3<\/th><th class=\"column-7\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 1<\/th><th class=\"column-8\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 2<\/th><th class=\"column-9\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 3<\/th><th class=\"column-10\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 1<\/th><th class=\"column-11\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 2<\/th><th class=\"column-12\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 3<\/th><th class=\"column-13\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 1<\/th><th class=\"column-14\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 2<\/th><th class=\"column-15\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 3<\/th><th class=\"column-16\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 1<\/th><th class=\"column-17\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 2<\/th><th class=\"column-18\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 3<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">BOURGEOIS Cl\u00e9ment<\/td><td class=\"column-3\">840<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">57<\/td><td class=\"column-6\">57<\/td><td class=\"column-7\">57<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">60<\/td><td class=\"column-10\">51<\/td><td class=\"column-11\">54<\/td><td class=\"column-12\">55<\/td><td class=\"column-13\">54<\/td><td class=\"column-14\">60<\/td><td class=\"column-15\">57<\/td><td class=\"column-16\">57<\/td><td class=\"column-17\">54<\/td><td class=\"column-18\">57<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">TOBIAS Schwieren<\/td><td class=\"column-3\">824<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">50<\/td><td class=\"column-6\">60<\/td><td class=\"column-7\">60<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">60<\/td><td class=\"column-11\">60<\/td><td class=\"column-12\">60<\/td><td class=\"column-13\">60<\/td><td class=\"column-14\">57<\/td><td class=\"column-15\">60<\/td><td class=\"column-16\">60<\/td><td class=\"column-17\">57<\/td><td class=\"column-18\">60<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">GOLARD EMY<\/td><td class=\"column-3\">794<\/td><td class=\"column-4\">52<\/td><td class=\"column-5\">53<\/td><td class=\"column-6\">46<\/td><td class=\"column-7\">55<\/td><td class=\"column-8\">52<\/td><td class=\"column-9\">55<\/td><td class=\"column-10\">52<\/td><td class=\"column-11\">57<\/td><td class=\"column-12\">57<\/td><td class=\"column-13\">52<\/td><td class=\"column-14\">48<\/td><td class=\"column-15\">50<\/td><td class=\"column-16\">52<\/td><td class=\"column-17\">60<\/td><td class=\"column-18\">53<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">RICCOBENE Gaetano<\/td><td class=\"column-3\">785<\/td><td class=\"column-4\">47<\/td><td class=\"column-5\">47<\/td><td class=\"column-6\">49<\/td><td class=\"column-7\">52<\/td><td class=\"column-8\">53<\/td><td class=\"column-9\">53<\/td><td class=\"column-10\">55<\/td><td class=\"column-11\">51<\/td><td class=\"column-12\">51<\/td><td class=\"column-13\">57<\/td><td class=\"column-14\">55<\/td><td class=\"column-15\">55<\/td><td class=\"column-16\">55<\/td><td class=\"column-17\">53<\/td><td class=\"column-18\">52<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">HEBETTE Nolan<\/td><td class=\"column-3\">784<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">55<\/td><td class=\"column-7\">48<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">52<\/td><td class=\"column-10\">53<\/td><td class=\"column-11\">52<\/td><td class=\"column-12\">49<\/td><td class=\"column-13\">53<\/td><td class=\"column-14\">53<\/td><td class=\"column-15\">54<\/td><td class=\"column-16\">54<\/td><td class=\"column-17\">52<\/td><td class=\"column-18\">50<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">DECENDRE Pol<\/td><td class=\"column-3\">781<\/td><td class=\"column-4\">57<\/td><td class=\"column-5\">52<\/td><td class=\"column-6\">54<\/td><td class=\"column-7\">51<\/td><td class=\"column-8\">51<\/td><td class=\"column-9\">51<\/td><td class=\"column-10\">49<\/td><td class=\"column-11\">48<\/td><td class=\"column-12\">52<\/td><td class=\"column-13\">55<\/td><td class=\"column-14\">52<\/td><td class=\"column-15\">53<\/td><td class=\"column-16\">51<\/td><td class=\"column-17\">51<\/td><td class=\"column-18\">54<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">GOLOS Liam<\/td><td class=\"column-3\">779<\/td><td class=\"column-4\">51<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">53<\/td><td class=\"column-7\">54<\/td><td class=\"column-8\">57<\/td><td class=\"column-9\">54<\/td><td class=\"column-10\">54<\/td><td class=\"column-11\">53<\/td><td class=\"column-12\">53<\/td><td class=\"column-13\">50<\/td><td class=\"column-14\">49<\/td><td class=\"column-15\">48<\/td><td class=\"column-16\">48<\/td><td class=\"column-17\">49<\/td><td class=\"column-18\">51<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">SURKIJN Emilien<\/td><td class=\"column-3\">771<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">51<\/td><td class=\"column-6\">51<\/td><td class=\"column-7\">50<\/td><td class=\"column-8\">49<\/td><td class=\"column-9\">50<\/td><td class=\"column-10\">50<\/td><td class=\"column-11\">50<\/td><td class=\"column-12\">50<\/td><td class=\"column-13\">51<\/td><td class=\"column-14\">54<\/td><td class=\"column-15\">52<\/td><td class=\"column-16\">53<\/td><td class=\"column-17\">55<\/td><td class=\"column-18\">55<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">LALLEMAND Lohan<\/td><td class=\"column-3\">718<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\">50<\/td><td class=\"column-7\">49<\/td><td class=\"column-8\">48<\/td><td class=\"column-9\">49<\/td><td class=\"column-10\">47<\/td><td class=\"column-11\">46<\/td><td class=\"column-12\">48<\/td><td class=\"column-13\">48<\/td><td class=\"column-14\">50<\/td><td class=\"column-15\">51<\/td><td class=\"column-16\">47<\/td><td class=\"column-17\">47<\/td><td class=\"column-18\">48<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">MEUNIER Mathys<\/td><td class=\"column-3\">683<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">44<\/td><td class=\"column-6\">45<\/td><td class=\"column-7\">45<\/td><td class=\"column-8\">47<\/td><td class=\"column-9\">46<\/td><td class=\"column-10\">44<\/td><td class=\"column-11\">44<\/td><td class=\"column-12\">46<\/td><td class=\"column-13\">46<\/td><td class=\"column-14\">51<\/td><td class=\"column-15\">45<\/td><td class=\"column-16\">46<\/td><td class=\"column-17\">42<\/td><td class=\"column-18\">46<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">KRUKOWSKI Savana<\/td><td class=\"column-3\">660<\/td><td class=\"column-4\">40<\/td><td class=\"column-5\">43<\/td><td class=\"column-6\">43<\/td><td class=\"column-7\">43<\/td><td class=\"column-8\">43<\/td><td class=\"column-9\">45<\/td><td class=\"column-10\">43<\/td><td class=\"column-11\">43<\/td><td class=\"column-12\">45<\/td><td class=\"column-13\">47<\/td><td class=\"column-14\">46<\/td><td class=\"column-15\">46<\/td><td class=\"column-16\">42<\/td><td class=\"column-17\">46<\/td><td class=\"column-18\">45<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">BASTIN Tim<\/td><td class=\"column-3\">566<\/td><td class=\"column-4\">48<\/td><td class=\"column-5\">46<\/td><td class=\"column-6\">52<\/td><td class=\"column-7\">47<\/td><td class=\"column-8\">46<\/td><td class=\"column-9\">48<\/td><td class=\"column-10\">45<\/td><td class=\"column-11\">45<\/td><td class=\"column-12\">44<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">50<\/td><td class=\"column-17\">48<\/td><td class=\"column-18\">47<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">MASSEGLIA Noa<\/td><td class=\"column-3\">526<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">42<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">43<\/td><td class=\"column-10\">42<\/td><td class=\"column-11\">42<\/td><td class=\"column-12\">43<\/td><td class=\"column-13\">45<\/td><td class=\"column-14\">45<\/td><td class=\"column-15\">47<\/td><td class=\"column-16\">45<\/td><td class=\"column-17\">45<\/td><td class=\"column-18\">43<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">MOUSTIER Isaac<\/td><td class=\"column-3\">429<\/td><td class=\"column-4\">53<\/td><td class=\"column-5\">54<\/td><td class=\"column-6\">48<\/td><td class=\"column-7\">46<\/td><td class=\"column-8\">41<\/td><td class=\"column-9\">42<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">49<\/td><td class=\"column-14\">47<\/td><td class=\"column-15\">49<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">BISCEGLIA Enzo<\/td><td class=\"column-3\">331<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">53<\/td><td class=\"column-8\">54<\/td><td class=\"column-9\">57<\/td><td class=\"column-10\">57<\/td><td class=\"column-11\">56<\/td><td class=\"column-12\">54<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">DETHY Emeric<\/td><td class=\"column-3\">288<\/td><td class=\"column-4\">54<\/td><td class=\"column-5\">49<\/td><td class=\"column-6\">41<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">48<\/td><td class=\"column-11\">49<\/td><td class=\"column-12\">47<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">DELFORGE Simon<\/td><td class=\"column-3\">272<\/td><td class=\"column-4\">43<\/td><td class=\"column-5\">48<\/td><td class=\"column-6\">47<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">46<\/td><td class=\"column-11\">47<\/td><td class=\"column-12\">41<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">DEVERGNIES EMILIEN<\/td><td class=\"column-3\">261<\/td><td class=\"column-4\">44<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">44<\/td><td class=\"column-7\">44<\/td><td class=\"column-8\">42<\/td><td class=\"column-9\">47<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">RAGUET Matisse-Aita<\/td><td class=\"column-3\">148<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">49<\/td><td class=\"column-17\">50<\/td><td class=\"column-18\">49<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">ABRAHAM Daniel<\/td><td class=\"column-3\">132<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">44<\/td><td class=\"column-17\">44<\/td><td class=\"column-18\">44<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">DAVIDE Scarpone<\/td><td class=\"column-3\">132<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">44<\/td><td class=\"column-14\">44<\/td><td class=\"column-15\">44<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">OLIVIER Math\u00e9o<\/td><td class=\"column-3\">130<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">41<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">44<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">SERONT Driss<\/td><td class=\"column-3\">128<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">43<\/td><td class=\"column-17\">43<\/td><td class=\"column-18\">42<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">MUSSO Gabriel<\/td><td class=\"column-3\">126<\/td><td class=\"column-4\">42<\/td><td class=\"column-5\">42<\/td><td class=\"column-6\">42<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">RUMMENS Edouard<\/td><td class=\"column-3\">124<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">41<\/td><td class=\"column-11\">41<\/td><td class=\"column-12\">42<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">MARACHE Bastien<\/td><td class=\"column-3\">122<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">41<\/td><td class=\"column-17\">40<\/td><td class=\"column-18\">41<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">RASQUIN Victor<\/td><td class=\"column-3\">122<\/td><td class=\"column-4\">41<\/td><td class=\"column-5\">41<\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">0<\/td><td class=\"column-17\">0<\/td><td class=\"column-18\">0<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">LENOIR Antoine<\/td><td class=\"column-3\">121<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">40<\/td><td class=\"column-17\">41<\/td><td class=\"column-18\">40<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">ULBRICH Michael<\/td><td class=\"column-3\">117<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">39<\/td><td class=\"column-17\">39<\/td><td class=\"column-18\">39<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">LOBET Victor<\/td><td class=\"column-3\">114<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td><td class=\"column-14\">0<\/td><td class=\"column-15\">0<\/td><td class=\"column-16\">38<\/td><td class=\"column-17\">38<\/td><td class=\"column-18\">38<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-25 from cache --><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-33 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-47 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-large-visibility\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-8 hover-type-none fusion-no-large-visibility\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/2026-KFT-SPRINT-jr-GENERAL.pdf\" target=\"_blank\" aria-label=\"Image7\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"261\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image7.png?resize=300%2C261&#038;ssl=1\" alt class=\"img-responsive wp-image-21555\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image7.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image7.png?resize=200%2C174&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image7.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image7.png?resize=400%2C349&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image7.png?fit=584%2C509&amp;ssl=1 584w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 300px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"CATEGFUN\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-34 has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-48 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-17\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 38px; line-height: 45px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CAT\u00c9GORIE FUN<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-35 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-49 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-spacing-right-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\">\n<table id=\"tablepress-23\" class=\"tablepress tablepress-id-23\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">CLASSEMENT<\/th><th class=\"column-2\">NOM<\/th><th class=\"column-3\">POINTS<\/th><th class=\"column-4\">ROUND 1<br \/>\n22-f\u00e9vr <br \/>\nRACE 1<\/th><th class=\"column-5\">ROUND 1<br \/>\n22-f\u00e9vr<br \/>\nRACE 2<\/th><th class=\"column-6\">ROUND 2<br \/>\n15-mar <br \/>\nRACE 1<\/th><th class=\"column-7\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 2<\/th><th class=\"column-8\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 1<\/th><th class=\"column-9\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 2<\/th><th class=\"column-10\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 1<\/th><th class=\"column-11\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 2<\/th><th class=\"column-12\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 1<\/th><th class=\"column-13\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 2<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">DELMOTTE Maxime<\/td><td class=\"column-3\">539<\/td><td class=\"column-4\">57<\/td><td class=\"column-5\">57<\/td><td class=\"column-6\">55<\/td><td class=\"column-7\">51<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">57<\/td><td class=\"column-10\">49<\/td><td class=\"column-11\">60<\/td><td class=\"column-12\">54<\/td><td class=\"column-13\">55<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">AUTHESERRE Matthieu<\/td><td class=\"column-3\">523<\/td><td class=\"column-4\">42<\/td><td class=\"column-5\">54<\/td><td class=\"column-6\">54<\/td><td class=\"column-7\">60<\/td><td class=\"column-8\">54<\/td><td class=\"column-9\">54<\/td><td class=\"column-10\">52<\/td><td class=\"column-11\">53<\/td><td class=\"column-12\">51<\/td><td class=\"column-13\">49<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">WATRIN Enzo<\/td><td class=\"column-3\">515<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">57<\/td><td class=\"column-7\">50<\/td><td class=\"column-8\">52<\/td><td class=\"column-9\">43<\/td><td class=\"column-10\">60<\/td><td class=\"column-11\">57<\/td><td class=\"column-12\">49<\/td><td class=\"column-13\">47<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">POTIER Jerome<\/td><td class=\"column-3\">513<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">44<\/td><td class=\"column-6\">45<\/td><td class=\"column-7\">48<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">60<\/td><td class=\"column-10\">51<\/td><td class=\"column-11\">54<\/td><td class=\"column-12\">53<\/td><td class=\"column-13\">48<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">SOETAERT Guillaume<\/td><td class=\"column-3\">474<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">53<\/td><td class=\"column-7\">52<\/td><td class=\"column-8\">43<\/td><td class=\"column-9\">42<\/td><td class=\"column-10\">53<\/td><td class=\"column-11\">49<\/td><td class=\"column-12\">34<\/td><td class=\"column-13\">43<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">VAN BRUSSELEN Alexis<\/td><td class=\"column-3\">460<\/td><td class=\"column-4\">48<\/td><td class=\"column-5\">48<\/td><td class=\"column-6\">42<\/td><td class=\"column-7\">38<\/td><td class=\"column-8\">42<\/td><td class=\"column-9\">40<\/td><td class=\"column-10\">54<\/td><td class=\"column-11\">48<\/td><td class=\"column-12\">47<\/td><td class=\"column-13\">53<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">BEGUIN Edouard<\/td><td class=\"column-3\">454<\/td><td class=\"column-4\">40<\/td><td class=\"column-5\">53<\/td><td class=\"column-6\">47<\/td><td class=\"column-7\">49<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">53<\/td><td class=\"column-10\">43<\/td><td class=\"column-11\">51<\/td><td class=\"column-12\">41<\/td><td class=\"column-13\">32<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">DARMON Esteban<\/td><td class=\"column-3\">453<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">46<\/td><td class=\"column-6\">38<\/td><td class=\"column-7\">37<\/td><td class=\"column-8\">39<\/td><td class=\"column-9\">30<\/td><td class=\"column-10\">50<\/td><td class=\"column-11\">52<\/td><td class=\"column-12\">55<\/td><td class=\"column-13\">57<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">STEENS Lander<\/td><td class=\"column-3\">451<\/td><td class=\"column-4\">41<\/td><td class=\"column-5\">49<\/td><td class=\"column-6\">50<\/td><td class=\"column-7\">54<\/td><td class=\"column-8\">57<\/td><td class=\"column-9\">51<\/td><td class=\"column-10\">42<\/td><td class=\"column-11\">45<\/td><td class=\"column-12\">22<\/td><td class=\"column-13\">40<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">ALLARD Niki<\/td><td class=\"column-3\">446<\/td><td class=\"column-4\">52<\/td><td class=\"column-5\">39<\/td><td class=\"column-6\">44<\/td><td class=\"column-7\">45<\/td><td class=\"column-8\">46<\/td><td class=\"column-9\">37<\/td><td class=\"column-10\">44<\/td><td class=\"column-11\">50<\/td><td class=\"column-12\">45<\/td><td class=\"column-13\">44<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">HELLEMANS Nina<\/td><td class=\"column-3\">404<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">42<\/td><td class=\"column-6\">31<\/td><td class=\"column-7\">36<\/td><td class=\"column-8\">27<\/td><td class=\"column-9\">39<\/td><td class=\"column-10\">47<\/td><td class=\"column-11\">43<\/td><td class=\"column-12\">48<\/td><td class=\"column-13\">46<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">CHAVEZ Valentin<\/td><td class=\"column-3\">377<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">52<\/td><td class=\"column-7\">55<\/td><td class=\"column-8\">53<\/td><td class=\"column-9\">15<\/td><td class=\"column-10\">38<\/td><td class=\"column-11\">47<\/td><td class=\"column-12\">57<\/td><td class=\"column-13\">60<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">NAYOM\u00c9 Gregory<\/td><td class=\"column-3\">343<\/td><td class=\"column-4\">47<\/td><td class=\"column-5\">51<\/td><td class=\"column-6\">33<\/td><td class=\"column-7\">35<\/td><td class=\"column-8\">20<\/td><td class=\"column-9\">33<\/td><td class=\"column-10\">36<\/td><td class=\"column-11\">35<\/td><td class=\"column-12\">31<\/td><td class=\"column-13\">22<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">LOTHAIRE Emilien<\/td><td class=\"column-3\">342<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">46<\/td><td class=\"column-7\">46<\/td><td class=\"column-8\">28<\/td><td class=\"column-9\">44<\/td><td class=\"column-10\">46<\/td><td class=\"column-11\">44<\/td><td class=\"column-12\">46<\/td><td class=\"column-13\">42<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">VAN MALCOT Mika<\/td><td class=\"column-3\">336<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">60<\/td><td class=\"column-7\">57<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">47<\/td><td class=\"column-10\">57<\/td><td class=\"column-11\">55<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">MARTIN Anael<\/td><td class=\"column-3\">335<\/td><td class=\"column-4\">43<\/td><td class=\"column-5\">41<\/td><td class=\"column-6\">30<\/td><td class=\"column-7\">32<\/td><td class=\"column-8\">29<\/td><td class=\"column-9\">22<\/td><td class=\"column-10\">41<\/td><td class=\"column-11\">37<\/td><td class=\"column-12\">32<\/td><td class=\"column-13\">28<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">DE PRIESTER Geoffrey<\/td><td class=\"column-3\">301<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">49<\/td><td class=\"column-9\">48<\/td><td class=\"column-10\">55<\/td><td class=\"column-11\">46<\/td><td class=\"column-12\">52<\/td><td class=\"column-13\">51<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">DEFAUX Rosario<\/td><td class=\"column-3\">300<\/td><td class=\"column-4\">39<\/td><td class=\"column-5\">43<\/td><td class=\"column-6\">28<\/td><td class=\"column-7\">31<\/td><td class=\"column-8\">21<\/td><td class=\"column-9\">25<\/td><td class=\"column-10\">37<\/td><td class=\"column-11\">33<\/td><td class=\"column-12\">20<\/td><td class=\"column-13\">23<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">ZUBEK Josue<\/td><td class=\"column-3\">254<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">48<\/td><td class=\"column-7\">47<\/td><td class=\"column-8\">47<\/td><td class=\"column-9\">49<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">24<\/td><td class=\"column-13\">39<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">GILLAIN Nigel<\/td><td class=\"column-3\">253<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">39<\/td><td class=\"column-7\">43<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">48<\/td><td class=\"column-11\">40<\/td><td class=\"column-12\">42<\/td><td class=\"column-13\">41<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">CHANTRENNE Nicolas<\/td><td class=\"column-3\">248<\/td><td class=\"column-4\">51<\/td><td class=\"column-5\">50<\/td><td class=\"column-6\">41<\/td><td class=\"column-7\">28<\/td><td class=\"column-8\">40<\/td><td class=\"column-9\">38<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">JACQUEMIN Bertrand<\/td><td class=\"column-3\">215<\/td><td class=\"column-4\">53<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">49<\/td><td class=\"column-7\">53<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">JOZEFIAK Alexandre<\/td><td class=\"column-3\">215<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">44<\/td><td class=\"column-8\">25<\/td><td class=\"column-9\">20<\/td><td class=\"column-10\">45<\/td><td class=\"column-11\">41<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">GEREIN Benjamin<\/td><td class=\"column-3\">206<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">26<\/td><td class=\"column-9\">29<\/td><td class=\"column-10\">35<\/td><td class=\"column-11\">36<\/td><td class=\"column-12\">43<\/td><td class=\"column-13\">37<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">BOSSIROY Guillaume<\/td><td class=\"column-3\">202<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">36<\/td><td class=\"column-7\">40<\/td><td class=\"column-8\">34<\/td><td class=\"column-9\">34<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">28<\/td><td class=\"column-13\">30<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">TORLET Corentin<\/td><td class=\"column-3\">193<\/td><td class=\"column-4\">44<\/td><td class=\"column-5\">47<\/td><td class=\"column-6\">29<\/td><td class=\"column-7\">29<\/td><td class=\"column-8\">23<\/td><td class=\"column-9\">21<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">BOSSIROY Bastien<\/td><td class=\"column-3\">189<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">35<\/td><td class=\"column-7\">33<\/td><td class=\"column-8\">30<\/td><td class=\"column-9\">32<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">35<\/td><td class=\"column-13\">24<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">VANDERBECK Cedric<\/td><td class=\"column-3\">181<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">32<\/td><td class=\"column-9\">45<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">50<\/td><td class=\"column-13\">54<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">DEBRUYNE Jimmy<\/td><td class=\"column-3\">180<\/td><td class=\"column-4\">54<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\">51<\/td><td class=\"column-7\">30<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">PECORARO Alessandro<\/td><td class=\"column-3\">174<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">32<\/td><td class=\"column-7\">39<\/td><td class=\"column-8\">24<\/td><td class=\"column-9\">26<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">27<\/td><td class=\"column-13\">26<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">BAUDOUIN Anthony<\/td><td class=\"column-3\">133<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">34<\/td><td class=\"column-11\">38<\/td><td class=\"column-12\">30<\/td><td class=\"column-13\">31<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\">NELLI Fabrice<\/td><td class=\"column-3\">116<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">34<\/td><td class=\"column-7\">34<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">21<\/td><td class=\"column-13\">27<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">SURKIJN Emilien<\/td><td class=\"column-3\">112<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">60<\/td><td class=\"column-13\">52<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">LEWAHERT Nathan<\/td><td class=\"column-3\">106<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">51<\/td><td class=\"column-9\">55<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">35<\/td><td class=\"column-2\">LOWIES Gaetan<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">15<\/td><td class=\"column-9\">18<\/td><td class=\"column-10\">33<\/td><td class=\"column-11\">34<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">CALMANT Florent<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">52<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">HERVE Elie<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">48<\/td><td class=\"column-9\">50<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">VIGNERON Lionel<\/td><td class=\"column-3\">96<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">46<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">39<\/td><td class=\"column-2\">LEGNAME Danilo<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">41<\/td><td class=\"column-9\">52<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">KUYPERS Florian<\/td><td class=\"column-3\">90<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">40<\/td><td class=\"column-13\">50<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">41<\/td><td class=\"column-2\">LIBERT Youri<\/td><td class=\"column-3\">85<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">43<\/td><td class=\"column-7\">42<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">42<\/td><td class=\"column-2\">PETIT Kevin<\/td><td class=\"column-3\">82<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">44<\/td><td class=\"column-13\">38<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">43<\/td><td class=\"column-2\">HUYGAERTS Randy<\/td><td class=\"column-3\">81<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">39<\/td><td class=\"column-11\">42<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">44<\/td><td class=\"column-2\">COPPI Antoni<\/td><td class=\"column-3\">79<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">40<\/td><td class=\"column-11\">39<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\">MISKOVEC Slavomir<\/td><td class=\"column-3\">78<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">37<\/td><td class=\"column-7\">41<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">46<\/td><td class=\"column-2\">SCIASCA Matt<\/td><td class=\"column-3\">76<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">35<\/td><td class=\"column-9\">41<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">47<\/td><td class=\"column-2\">STARKOV Sergii<\/td><td class=\"column-3\">74<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">38<\/td><td class=\"column-13\">36<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">48<\/td><td class=\"column-2\">DI TOMASO Cedric<\/td><td class=\"column-3\">72<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">39<\/td><td class=\"column-13\">33<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">VERLY Hugo<\/td><td class=\"column-3\">72<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">36<\/td><td class=\"column-9\">36<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\">MENTION Noah<\/td><td class=\"column-3\">71<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">26<\/td><td class=\"column-13\">45<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">51<\/td><td class=\"column-2\">MENTION Michael<\/td><td class=\"column-3\">70<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">36<\/td><td class=\"column-13\">34<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">52<\/td><td class=\"column-2\">MICHAUX Andy<\/td><td class=\"column-3\">68<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">37<\/td><td class=\"column-9\">31<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">VIGNERON Jonathan<\/td><td class=\"column-3\">68<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">33<\/td><td class=\"column-9\">35<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">54<\/td><td class=\"column-2\">BEUVIERE Ludo<\/td><td class=\"column-3\">62<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">33<\/td><td class=\"column-13\">29<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\">MOREAU Anthony<\/td><td class=\"column-3\">60<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">25<\/td><td class=\"column-13\">35<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">56<\/td><td class=\"column-2\">NICHOLS Karl<\/td><td class=\"column-3\">58<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">31<\/td><td class=\"column-9\">27<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">57<\/td><td class=\"column-2\">KOKKEN Dimitri<\/td><td class=\"column-3\">56<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">37<\/td><td class=\"column-13\">19<\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">58<\/td><td class=\"column-2\">TOMCZK Sebastien<\/td><td class=\"column-3\">55<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">38<\/td><td class=\"column-9\">17<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">59<\/td><td class=\"column-2\">PHILIPPE Christophe<\/td><td class=\"column-3\">47<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">29<\/td><td class=\"column-13\">18<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">SAYER Oliver<\/td><td class=\"column-3\">47<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">19<\/td><td class=\"column-9\">28<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">61<\/td><td class=\"column-2\">ZAHLEN Jean Luc<\/td><td class=\"column-3\">46<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">22<\/td><td class=\"column-9\">24<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">62<\/td><td class=\"column-2\">BAS Oran<\/td><td class=\"column-3\">44<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">23<\/td><td class=\"column-13\">21<\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">63<\/td><td class=\"column-2\">BIANCHI Arsenio<\/td><td class=\"column-3\">43<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">18<\/td><td class=\"column-13\">25<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">64<\/td><td class=\"column-2\">COPESTAKE Mike<\/td><td class=\"column-3\">40<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">17<\/td><td class=\"column-9\">23<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">65<\/td><td class=\"column-2\">CHAOUCH Zouhair<\/td><td class=\"column-3\">39<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">19<\/td><td class=\"column-13\">20<\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">66<\/td><td class=\"column-2\">CONTINO Aleandro Antonio<\/td><td class=\"column-3\">35<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">16<\/td><td class=\"column-9\">19<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">67<\/td><td class=\"column-2\">KRUKOWSKI Savana<\/td><td class=\"column-3\">34<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">18<\/td><td class=\"column-9\">16<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">JEANBART Patrick<\/td><td class=\"column-3\">34<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">17<\/td><td class=\"column-13\">17<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">69<\/td><td class=\"column-2\">SCREF Jacques<\/td><td class=\"column-3\">32<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">16<\/td><td class=\"column-13\">16<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-23 from cache --><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-36 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-50 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-large-visibility\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-9 hover-type-none fusion-no-large-visibility\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/2026-KFT-SPRINT-CLAS-FUN-gene.pdf\" target=\"_blank\" aria-label=\"Image8\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"262\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image8.png?resize=300%2C262&#038;ssl=1\" alt class=\"img-responsive wp-image-21556\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image8.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image8.png?resize=200%2C175&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image8.png?resize=300%2C262&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image8.png?resize=400%2C349&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image8.png?fit=584%2C510&amp;ssl=1 584w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 300px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"CATEGFUNLIGHT\" class=\"fusion-container-anchor\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-37 has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-background-image:radial-gradient(circle at center center, #14d500 0%,#000000 100%);;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-51 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:2px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-18\"><h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: Raleway; font-weight: 800; font-size: 40px; line-height: 63px;\" data-fusion-font=\"true\" data-fusion-google-font=\"Raleway\" data-fusion-google-variant=\"800\" data-fusion-google-subset=\"latin\">CAT\u00c9GORIE FUN LIGHT<\/span><\/h2>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-38 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-52 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-spacing-right-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\">\n<table id=\"tablepress-24\" class=\"tablepress tablepress-id-24\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">CLASSEMENT<\/th><th class=\"column-2\">NOM<\/th><th class=\"column-3\">POINTS<\/th><th class=\"column-4\">ROUND 1<br \/>\n22-f\u00e9vr<br \/>\nRACE 1<\/th><th class=\"column-5\">ROUND 1<br \/>\n22-f\u00e9vr<br \/>\nRACE 2<\/th><th class=\"column-6\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 1<\/th><th class=\"column-7\">ROUND 2<br \/>\n15-mar<br \/>\nRACE 2<\/th><th class=\"column-8\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 1<\/th><th class=\"column-9\">ROUND 3<br \/>\n26-avr<br \/>\nRACE 2<\/th><th class=\"column-10\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 1<\/th><th class=\"column-11\">ROUND 4<br \/>\n12-juil<br \/>\nRACE 2<\/th><th class=\"column-12\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 1<\/th><th class=\"column-13\">ROUND 5<br \/>\n30-ao\u00fbt<br \/>\nRACE 2<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">BOURGEOIS Cl\u00e9ment<\/td><td class=\"column-3\">567<\/td><td class=\"column-4\">57<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">60<\/td><td class=\"column-7\">60<\/td><td class=\"column-8\">54<\/td><td class=\"column-9\">54<\/td><td class=\"column-10\">57<\/td><td class=\"column-11\">60<\/td><td class=\"column-12\">50<\/td><td class=\"column-13\">60<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">GOLOS Liam<\/td><td class=\"column-3\">558<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">57<\/td><td class=\"column-7\">51<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">52<\/td><td class=\"column-10\">54<\/td><td class=\"column-11\">54<\/td><td class=\"column-12\">57<\/td><td class=\"column-13\">53<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">DELFOSSE Julie<\/td><td class=\"column-3\">470<\/td><td class=\"column-4\">52<\/td><td class=\"column-5\">53<\/td><td class=\"column-6\">41<\/td><td class=\"column-7\">40<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">44<\/td><td class=\"column-10\">52<\/td><td class=\"column-11\">50<\/td><td class=\"column-12\">47<\/td><td class=\"column-13\">46<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">NAYOM\u00c9 Lenny<\/td><td class=\"column-3\">466<\/td><td class=\"column-4\">48<\/td><td class=\"column-5\">46<\/td><td class=\"column-6\">47<\/td><td class=\"column-7\">46<\/td><td class=\"column-8\">47<\/td><td class=\"column-9\">45<\/td><td class=\"column-10\">50<\/td><td class=\"column-11\">52<\/td><td class=\"column-12\">41<\/td><td class=\"column-13\">44<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">DECENDRE Pol<\/td><td class=\"column-3\">444<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">54<\/td><td class=\"column-7\">57<\/td><td class=\"column-8\">52<\/td><td class=\"column-9\">53<\/td><td class=\"column-10\">60<\/td><td class=\"column-11\">57<\/td><td class=\"column-12\">54<\/td><td class=\"column-13\">57<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">RAUCQ Louis<\/td><td class=\"column-3\">403<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">44<\/td><td class=\"column-6\">39<\/td><td class=\"column-7\">39<\/td><td class=\"column-8\">43<\/td><td class=\"column-9\">43<\/td><td class=\"column-10\">40<\/td><td class=\"column-11\">41<\/td><td class=\"column-12\">35<\/td><td class=\"column-13\">34<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">BAILLIEZ Florian<\/td><td class=\"column-3\">359<\/td><td class=\"column-4\">47<\/td><td class=\"column-5\">49<\/td><td class=\"column-6\">42<\/td><td class=\"column-7\">42<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">49<\/td><td class=\"column-11\">45<\/td><td class=\"column-12\">43<\/td><td class=\"column-13\">42<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">CHANTRENNE Lucas<\/td><td class=\"column-3\">358<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">44<\/td><td class=\"column-7\">47<\/td><td class=\"column-8\">48<\/td><td class=\"column-9\">46<\/td><td class=\"column-10\">47<\/td><td class=\"column-11\">49<\/td><td class=\"column-12\">36<\/td><td class=\"column-13\">41<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">HEBETTE Nolan<\/td><td class=\"column-3\">331<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">60<\/td><td class=\"column-10\">55<\/td><td class=\"column-11\">55<\/td><td class=\"column-12\">52<\/td><td class=\"column-13\">54<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">VANSTEENACKER Keld<\/td><td class=\"column-3\">319<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">57<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">51<\/td><td class=\"column-9\">50<\/td><td class=\"column-10\">53<\/td><td class=\"column-11\">53<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">POLART Noah<\/td><td class=\"column-3\">285<\/td><td class=\"column-4\">53<\/td><td class=\"column-5\">48<\/td><td class=\"column-6\">43<\/td><td class=\"column-7\">43<\/td><td class=\"column-8\">49<\/td><td class=\"column-9\">49<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">SURKIJN Emilien<\/td><td class=\"column-3\">216<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">53<\/td><td class=\"column-7\">55<\/td><td class=\"column-8\">53<\/td><td class=\"column-9\">55<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">DEMURIE Jean-Luc<\/td><td class=\"column-3\">206<\/td><td class=\"column-4\">51<\/td><td class=\"column-5\">52<\/td><td class=\"column-6\">50<\/td><td class=\"column-7\">53<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">LOGRILLO Vito Giacomo<\/td><td class=\"column-3\">203<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">51<\/td><td class=\"column-10\">51<\/td><td class=\"column-11\">51<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">WATRIN Enzo<\/td><td class=\"column-3\">196<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">48<\/td><td class=\"column-7\">54<\/td><td class=\"column-8\">46<\/td><td class=\"column-9\">48<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">BASTIN Tim<\/td><td class=\"column-3\">196<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">51<\/td><td class=\"column-7\">49<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">49<\/td><td class=\"column-13\">47<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">PARDONCHE Cl\u00e9ment<\/td><td class=\"column-3\">187<\/td><td class=\"column-4\">44<\/td><td class=\"column-5\">50<\/td><td class=\"column-6\">49<\/td><td class=\"column-7\">44<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">LIBERT Youri<\/td><td class=\"column-3\">187<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">47<\/td><td class=\"column-6\">45<\/td><td class=\"column-7\">45<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">MPETI LIEKE Anthony<\/td><td class=\"column-3\">185<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">46<\/td><td class=\"column-7\">48<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">46<\/td><td class=\"column-13\">45<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">PIRMEZ Flora<\/td><td class=\"column-3\">172<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">48<\/td><td class=\"column-11\">46<\/td><td class=\"column-12\">39<\/td><td class=\"column-13\">39<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">BISCEGLIA Enzo<\/td><td class=\"column-3\">114<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">57<\/td><td class=\"column-9\">57<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">KNAEPEN William<\/td><td class=\"column-3\">112<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">60<\/td><td class=\"column-13\">52<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">RICCOBENE Gaetano<\/td><td class=\"column-3\">110<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">55<\/td><td class=\"column-13\">55<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">MERCIER Antoine<\/td><td class=\"column-3\">108<\/td><td class=\"column-4\">54<\/td><td class=\"column-5\">54<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">MATON Noah<\/td><td class=\"column-3\">105<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">55<\/td><td class=\"column-7\">50<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">VOLCKAERTS Kyle<\/td><td class=\"column-3\">104<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">52<\/td><td class=\"column-7\">52<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">DE PRIESTER Geoffrey<\/td><td class=\"column-3\">103<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">53<\/td><td class=\"column-13\">50<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">DE RYUTER Andrew<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">51<\/td><td class=\"column-13\">49<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">GROHE Cassio<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">51<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">CHAVEZ Valentin<\/td><td class=\"column-3\">99<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">48<\/td><td class=\"column-13\">51<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">KRUKOWSKI Savana<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">45<\/td><td class=\"column-13\">48<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">BEGHIN Pierr-Marie<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">46<\/td><td class=\"column-11\">47<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">33<\/td><td class=\"column-2\">DURISOTTI S\u00e9bastien<\/td><td class=\"column-3\">92<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">44<\/td><td class=\"column-11\">48<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">DIEUDONNE Steve<\/td><td class=\"column-3\">91<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">47<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">KARTHAUSER Alexis<\/td><td class=\"column-3\">91<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">RINGUET Ga\u00ebtan<\/td><td class=\"column-3\">89<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">45<\/td><td class=\"column-11\">44<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">37<\/td><td class=\"column-2\">HELLEMANS Nina<\/td><td class=\"column-3\">87<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">44<\/td><td class=\"column-13\">43<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">WELKIN Maheo<\/td><td class=\"column-3\">84<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">41<\/td><td class=\"column-11\">43<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">DUCANCHEZ Aymeric<\/td><td class=\"column-3\">84<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">42<\/td><td class=\"column-11\">42<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">MASSART Thimoth\u00e9e<\/td><td class=\"column-3\">82<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">43<\/td><td class=\"column-11\">39<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">URBAIN Florent<\/td><td class=\"column-3\">82<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">42<\/td><td class=\"column-13\">40<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">42<\/td><td class=\"column-2\">CATHERINE Pascal<\/td><td class=\"column-3\">81<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">41<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">43<\/td><td class=\"column-2\">PRIMAVERA Th\u00e9o<\/td><td class=\"column-3\">79<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">39<\/td><td class=\"column-11\">40<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">44<\/td><td class=\"column-2\">MARACHE Fr\u00e9d\u00e9ric<\/td><td class=\"column-3\">78<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">40<\/td><td class=\"column-13\">38<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\">DURISOTTI Raphael<\/td><td class=\"column-3\">76<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">38<\/td><td class=\"column-11\">38<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">VAN DEN BERGE Justin<\/td><td class=\"column-3\">76<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">38<\/td><td class=\"column-7\">38<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">47<\/td><td class=\"column-2\">GEREIN Benjamin<\/td><td class=\"column-3\">75<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">38<\/td><td class=\"column-13\">37<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">48<\/td><td class=\"column-2\">PARDONCHE Dominique<\/td><td class=\"column-3\">74<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">37<\/td><td class=\"column-7\">37<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">49<\/td><td class=\"column-2\">MAKUCH Jonathan<\/td><td class=\"column-3\">72<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">37<\/td><td class=\"column-13\">35<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">VAN DEN BERGE Vivien<\/td><td class=\"column-3\">72<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">36<\/td><td class=\"column-7\">36<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">0<\/td><td class=\"column-13\">0<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">51<\/td><td class=\"column-2\">VANDIEVOET Laurent<\/td><td class=\"column-3\">68<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">32<\/td><td class=\"column-13\">36<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">52<\/td><td class=\"column-2\">MAICO Minne<\/td><td class=\"column-3\">66<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">34<\/td><td class=\"column-13\">32<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">LOTHAIRE Emilien<\/td><td class=\"column-3\">66<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">33<\/td><td class=\"column-13\">33<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">54<\/td><td class=\"column-2\">LEEMPOEL Kevin<\/td><td class=\"column-3\">61<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">30<\/td><td class=\"column-13\">31<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\">SOYEURT Julien<\/td><td class=\"column-3\">60<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">31<\/td><td class=\"column-13\">29<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">56<\/td><td class=\"column-2\">MAEYENS Liam<\/td><td class=\"column-3\">59<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">29<\/td><td class=\"column-13\">30<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">57<\/td><td class=\"column-2\">BION Jonathan<\/td><td class=\"column-3\">56<\/td><td class=\"column-4\">0<\/td><td class=\"column-5\">0<\/td><td class=\"column-6\">0<\/td><td class=\"column-7\">0<\/td><td class=\"column-8\">0<\/td><td class=\"column-9\">0<\/td><td class=\"column-10\">0<\/td><td class=\"column-11\">0<\/td><td class=\"column-12\">28<\/td><td class=\"column-13\">28<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-24 from cache --><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-39 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-53 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-spacing-right-large:1.92%;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-large-visibility\" style=\"text-align:center;\"><span class=\"fusion-imageframe imageframe-none imageframe-10 hover-type-none fusion-no-large-visibility\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/08\/2026-KFT-SPRINT-CLAS-FUN-light-gene.pdf\" target=\"_blank\" aria-label=\"Image9\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"261\" src=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image9.png?resize=300%2C261&#038;ssl=1\" alt class=\"img-responsive wp-image-21557\" srcset=\"https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image9.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image9.png?resize=200%2C174&amp;ssl=1 200w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image9.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image9.png?resize=400%2C349&amp;ssl=1 400w, https:\/\/i0.wp.com\/kartingdesfagnes.be\/wp-content\/uploads\/2026\/02\/Image9.png?fit=584%2C509&amp;ssl=1 584w\" sizes=\"(max-width: 1272px) 100vw, (max-width: 1034px) 100vw, 300px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-40 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#000000;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-54 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-section-separator section-separator slant fusion-section-separator-1\" style=\"--awb-spacer-height:99px;--awb-svg-margin-left:0;--awb-svg-margin-right:0;--awb-divider-height:99px;--awb-spacer-padding-top:inherit;--awb-sep-padding:0;--awb-svg-padding:0;\"><div class=\"fusion-section-separator-svg\"><svg class=\"fusion-slant-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" height=\"100\" viewbox=\"0 0 100 100\" preserveaspectratio=\"none\" fill=\"rgba(20,213,0,1)\"><path d=\"M0 100 L0 0 L100 0 Z\"><\/path><\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-13536","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/pages\/13536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/comments?post=13536"}],"version-history":[{"count":438,"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/pages\/13536\/revisions"}],"predecessor-version":[{"id":21971,"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/pages\/13536\/revisions\/21971"}],"wp:attachment":[{"href":"https:\/\/kartingdesfagnes.be\/nl\/wp-json\/wp\/v2\/media?parent=13536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}